{"id":971,"date":"2023-08-30T08:18:00","date_gmt":"2023-08-30T08:18:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=971"},"modified":"2023-09-02T20:20:40","modified_gmt":"2023-09-02T20:20:40","slug":"homero-martinez-destaco-los-resultados-y-estabilidad-del-municipio-de-lerdo","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/homero-martinez-destaco-los-resultados-y-estabilidad-del-municipio-de-lerdo\/","title":{"rendered":"Homero Mart\u00ednez destac\u00f3 los resultados y estabilidad del municipio de Lerdo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Se aplicaron m\u00e1s de 100 obras sociales y 25 mil atenciones<\/h2>\n\n\n\n<p>30 de agosto de 2023. Destacando la inversi\u00f3n de m\u00e1s de 130 millones de pesos a trav\u00e9s de m\u00e1s de cien obras sociales que han permitido un avance importante en el desarrollo urbano y econ\u00f3mico de Lerdo, el alcalde Homero Mart\u00ednez tras rendir su primer informe de gobierno asegur\u00f3 que se ha podido rendir buenos resultados a la ciudadan\u00eda para contar con un Lerdo estable en finanzas y cumplimiento en los servicios.<\/p>\n\n\n\n<p>El informe tuvo verificativo este mi\u00e9rcoles en el Teatro Hermila Galindo, donde se cont\u00f3 con casi la mayor\u00eda de los diputados del Congreso del Estado, as\u00ed como del secretario de Educaci\u00f3n en el estado, Guillermo Adame Calder\u00f3n en representaci\u00f3n del gobernador Esteban Villegas.<\/p>\n\n\n\n<p>Asimismo present\u00f3 un informe sobre el ejercicio de gobierno; las decisiones de pol\u00edticas p\u00fablicas, el origen y destino de los recursos aplicados en la administraci\u00f3n de la hacienda municipal.<\/p>\n\n\n\n<p>En b\u00fasqueda por un camino con enfoque integral, transversalmente sustentable y sostenible, en Lerdo se llevaron a cabo diversas acciones para abarcar los principales temas que integran el Plan Municipal de Desarrollo 2022 &#8211; 2025, aplicando los 5 ejes rectores para garantizar el \u00e9xito de un trabajo organizado, planificado y acorde a las condiciones del municipio.<\/p>\n\n\n\n<p>&nbsp;\u201cEl compromiso que adquirimos desde el primer d\u00eda de mi gobierno, lo hemos cumplido a cabalidad, gracias a ello, hoy en Lerdo se vive mejor, con un ambiente de paz y tranquilidad social\u201d, precis\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s, dando continuidad a los planes y proyectos para ejercer en un gobierno honesto, responsable, ordenado y humano, se enfrentaron desaf\u00edos, cumpliendo compromisos con la gente, a trav\u00e9s de un gobierno cercano con audiencias p\u00fablicas y cabildo abierto, atendiendo los temas de agua potable, drenaje, recolecci\u00f3n de basura, alumbrado p\u00fablico, salud, prevenci\u00f3n social, deporte, cultura, pavimentaci\u00f3n, y apoyos sociales.<\/p>\n\n\n\n<p>Mejorando los servicios, siendo el primer municipio en apostarle a la digitalizaci\u00f3n con el cien por ciento de sus tr\u00e1mites en l\u00ednea, y el que a nivel estatal m\u00e1s ingresos propios porcentualmente recaud\u00f3 con un incremento en t\u00e9rminos reales del 34% del actual ejercicio en comparaci\u00f3n con el 2019. Ingresos que beneficiaron a la poblaci\u00f3n con m\u00e1s obras y mejores servicios.<\/p>\n\n\n\n<p>En el tema de seguridad, se equipo a los polic\u00edas municipales, dot\u00e1ndolos adem\u00e1s de patrullas y entreg\u00e1ndoles est\u00edmulos econ\u00f3micos bono por cada detenci\u00f3n que pusieran a disposici\u00f3n del ministerio p\u00fablico y que esto permitiera bajar el \u00edndice delictivo de robo a casa habitaci\u00f3n y robo a negocio, garantizando la tranquilidad de la gente.<\/p>\n\n\n\n<p>\u201cHoy en d\u00eda, Lerdo forma parte de los 100 municipios m\u00e1s seguros del pa\u00eds\u201d aprovech\u00f3 para agradecer el respaldo de la SEDENA y el Mando Especial en La Laguna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se aplicaron m\u00e1s de 100 obras sociales y 25 mil atenciones 30 de agosto de 2023. Destacando la inversi\u00f3n de m\u00e1s de 130 millones de pesos a trav\u00e9s de m\u00e1s de cien obras sociales que han permitido un avance importante en el desarrollo urbano y econ\u00f3mico de Lerdo, el alcalde Homero Mart\u00ednez tras rendir su&#8230;<\/p>\n","protected":false},"author":1,"featured_media":972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=971"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/971\/revisions"}],"predecessor-version":[{"id":973,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/971\/revisions\/973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/972"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}