{"id":893,"date":"2023-08-25T07:03:00","date_gmt":"2023-08-25T07:03:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=893"},"modified":"2023-08-28T19:06:23","modified_gmt":"2023-08-28T19:06:23","slug":"viajar-en-durango-es-seguro-oscar-galvan","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/viajar-en-durango-es-seguro-oscar-galvan\/","title":{"rendered":"Viajar en Durango es seguro: Oscar Galv\u00e1n"},"content":{"rendered":"\n<p>El secretario de Seguridad habl\u00f3 sobre la alerta que emiti\u00f3 la embajada de EU que refiere no viajar en la carretera Zacatecas-Durango Durango es un estado seguro para viajar, coment\u00f3 el secretario de Seguridad, comisionado Oscar Galv\u00e1n Villarreal, al referirse a la alerta que emiti\u00f3 la embajada de Estados Unidos que refiere no viajar en la carretera federal Zacatecas-Durango.<\/p>\n\n\n\n<p>25 de agosto de 2023. Explic\u00f3 que el documento solo se refiere a un tramo de carretera federal que va de Zacatecas a Durango y subray\u00f3 que existe un dispositivo carretero importante en tema de seguridad tanto en el estado de Durango como en Zacatecas.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que Durango est\u00e1 blindado y existe tranquilidad y paz, adem\u00e1s record\u00f3 que existe un convenio fortalecido en materia de seguridad con Zacatecas, quien de la mano con la Guardia Nacional resguardan las v\u00edas carreteras que colindan con Durango.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que en el primer a\u00f1o de trabajo de la administraci\u00f3n estatal se ha logrado obtener recursos para tener un esquema de seguridad fortalecido y ahora el cien por ciento de las corporaciones de seguridad est\u00e1n certificadas, adem\u00e1s se cuenta con el Mando \u00danico y en coordinaci\u00f3n con las diversas instituciones de seguridad se tienen un estado seguro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Seguridad habl\u00f3 sobre la alerta que emiti\u00f3 la embajada de EU que refiere no viajar en la carretera Zacatecas-Durango Durango es un estado seguro para viajar, coment\u00f3 el secretario de Seguridad, comisionado Oscar Galv\u00e1n Villarreal, al referirse a la alerta que emiti\u00f3 la embajada de Estados Unidos que refiere no viajar en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-893","post","type-post","status-publish","format-standard","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=893"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/893\/revisions"}],"predecessor-version":[{"id":894,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/893\/revisions\/894"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}