{"id":839,"date":"2023-08-10T03:07:02","date_gmt":"2023-08-10T03:07:02","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=839"},"modified":"2023-08-17T03:08:46","modified_gmt":"2023-08-17T03:08:46","slug":"elaboraran-libro-blanco-sobre-caso-de-los-ex-trabajadores-municipales-panistas","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/elaboraran-libro-blanco-sobre-caso-de-los-ex-trabajadores-municipales-panistas\/","title":{"rendered":"Elaborar\u00e1n \u2018libro blanco\u2019 sobre caso de los ex trabajadores municipales panistas"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">En d\u00edas pasados se le pag\u00f3 un mill\u00f3n de pesos a uno por llegar a un buen acuerdo<\/h2>\n\n\n\n<p>10 de agosto de 2023. Despu\u00e9s de la sesi\u00f3n ordinaria de Cabildo, el alcalde Homero Mart\u00ednez inform\u00f3 que el ayuntamiento de Lerdo concret\u00f3 la indemnizaci\u00f3n a uno de los ex trabajadores municipales panistas a finales del a\u00f1o 2007 demandaron al Municipio por presunto despido injustificado.<\/p>\n\n\n\n<p>Al mismo tiempo, el presidente municipal lanz\u00f3 un exhorto al resto de los 54 ex trabajadores para que consideren al ayuntamiento de Lerdo para llegar a un arreglo real de las indemnizaciones.<\/p>\n\n\n\n<p>Enseguida indic\u00f3 que el arreglo y la consideraci\u00f3n del ex trabajador, fue que de tres millones de pesos, se acord\u00f3 pagar un mill\u00f3n de pesos para considerar las finanzas del municipio, de ah\u00ed que le reconoci\u00f3 la buena voluntad.<\/p>\n\n\n\n<p>\u201cCon este acuerdo, s\u00f3lo resta pagar a 54 ex trabajadores de los 120 que hab\u00edan demandado en materia laboral, por lo que representan 148 millones de pesos por pagar por el ayuntamiento de Lerdo\u201d, subray\u00f3.<\/p>\n\n\n\n<p>A su vez agreg\u00f3 que la autoridad municipal generar\u00e1 un libro blanco con las fechas en las que inici\u00f3 el procesos legal laboral, con cada uno de los nombres de los ex trabajadores y ex funcionarios que demandaron, a quienes se les finiquit\u00f3 y con qu\u00e9 monto, quienes fueron los abogados y cu\u00e1nto se ha erogado a lo largo de las administraciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En d\u00edas pasados se le pag\u00f3 un mill\u00f3n de pesos a uno por llegar a un buen acuerdo 10 de agosto de 2023. Despu\u00e9s de la sesi\u00f3n ordinaria de Cabildo, el alcalde Homero Mart\u00ednez inform\u00f3 que el ayuntamiento de Lerdo concret\u00f3 la indemnizaci\u00f3n a uno de los ex trabajadores municipales panistas a finales del a\u00f1o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-839","post","type-post","status-publish","format-standard","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=839"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/839\/revisions"}],"predecessor-version":[{"id":840,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/839\/revisions\/840"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}