{"id":806,"date":"2023-08-14T02:42:58","date_gmt":"2023-08-14T02:42:58","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=806"},"modified":"2023-08-17T02:47:19","modified_gmt":"2023-08-17T02:47:19","slug":"tras-24-anos-de-no-meterle-mano-esteban-moderniza-el-camino-a-dolores-hidalgo","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/tras-24-anos-de-no-meterle-mano-esteban-moderniza-el-camino-a-dolores-hidalgo\/","title":{"rendered":"Tras 24 a\u00f1os de no meterle mano, Esteban moderniza el camino a Dolores Hidalgo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Responde Gobernador a las familias de la comunidad con ruta&nbsp; segura e iluminada.<\/h2>\n\n\n\n<p>14 de agosto de 2023.Este camino estaba en condiciones lamentables, ya era un reclamo que la gente nos hac\u00eda, es por eso que se le meti\u00f3 mano para que los habitantes de Dolores Hidalgo, cuenten con seguridad en sus traslados, expres\u00f3 el gobernador Esteban Villegas Villarreal, al entregar la modernizaci\u00f3n de esta v\u00eda que ten\u00eda m\u00e1s de 24 a\u00f1os sin atenci\u00f3n.<\/p>\n\n\n\n<p>Es un tramo de seis kil\u00f3metros, donde ya casi no se pod\u00eda circular, pero ahora con esta rehabilitaci\u00f3n que se realiz\u00f3, les garantizamos que todos podr\u00e1n transitarla con facilidad y seguridad, destac\u00f3 el Mandatario Estatal al detallar que&nbsp; dentro de los trabajos, se efectu\u00f3 la aplicaci\u00f3n de riego de sello, se\u00f1alamiento horizontal y vertical con pintura reflejante para que en la noche se pueda pasar sin percances, adem\u00e1s, se construyeron banquetas, guarniciones y se pusieron luminarias.<\/p>\n\n\n\n<p>Jorge Armando Berm\u00fadez Guerrero, presidente de la Junta Municipal de Dolores Hidalgo, destac\u00f3 que el Gobernador llev\u00f3 un cambio muy necesario para la comunidad, ya que desde hace 24 a\u00f1os no se le met\u00eda mano a este espacio; hoy representa&nbsp; mejores condiciones de vida para los habitantes.<\/p>\n\n\n\n<p>M\u00e1s de mil 760 personas de este poblado, se benefician con esta soluci\u00f3n que el Gobernador brind\u00f3 y que impacta a la vialidad de la ciudad, agreg\u00f3&nbsp; Berm\u00fadez Guerrero.<\/p>\n\n\n\n<p>La titular de la Secretar\u00eda de Comunicaciones y Obras P\u00fablicas (SECOPE), Ana Rosa Hern\u00e1ndez Renter\u00eda, record\u00f3 que antes, cuando est\u00e9 camino estaba intransitable, hab\u00eda que&nbsp; darle la vuelta hasta el Perif\u00e9rico, sin embargo, ahora se ha convertido en&nbsp; una ruta alterna para pasar de la carretera al Mezquital a la M\u00e9xico, por ello, es de suma importancia que&nbsp; cuente con la iluminaci\u00f3n adecuada para evitar accidentes.<\/p>\n\n\n\n<p>Por su parte, el alcalde capitalino, Jos\u00e9 Antonio Ochoa, destac\u00f3 que el gobernador cumple con su palabra de ayudar las causas que m\u00e1s necesitan los duranguenses, ya que esta obra es un camino que da conectividad social, econ\u00f3mica y hasta educativa, porque es fundamental que los alumnos tengan una v\u00eda segura para llegar a las escuelas.<\/p>\n\n\n\n<p>&nbsp;\u201cEn coordinaci\u00f3n estamos haciendo obras trascendentales para la gente de Durango y damos resultados con un trabajo en conjunto\u201d, agreg\u00f3 el presidente municipal.<\/p>\n\n\n\n<p>En su visita a esta comunidad, Villegas Villarreal escuch\u00f3 diversas inquietudes de&nbsp; los vecinos del lugar, con quienes se comprometi\u00f3 a darles seguimiento y respuesta inmediata a cada una de sus peticiones y demandas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Responde Gobernador a las familias de la comunidad con ruta&nbsp; segura e iluminada. 14 de agosto de 2023.Este camino estaba en condiciones lamentables, ya era un reclamo que la gente nos hac\u00eda, es por eso que se le meti\u00f3 mano para que los habitantes de Dolores Hidalgo, cuenten con seguridad en sus traslados, expres\u00f3 el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=806"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/806\/revisions"}],"predecessor-version":[{"id":808,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/806\/revisions\/808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/807"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}