{"id":518,"date":"2023-07-06T18:08:49","date_gmt":"2023-07-06T18:08:49","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=518"},"modified":"2023-07-06T18:08:49","modified_gmt":"2023-07-06T18:08:49","slug":"homero-martinez-exhorta-a-no-ingresar-en-canales-y-rio-nazas","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/homero-martinez-exhorta-a-no-ingresar-en-canales-y-rio-nazas\/","title":{"rendered":"Homero Mart\u00ednez exhorta a no ingresar en canales y R\u00edo Nazas"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ha hecho un llamado urgente a los padres de familia<\/h2>\n\n\n\n<p>06 de julio de 2023. Lerdo, Durango.- El Alcalde de Lerdo, Homero Mart\u00ednez Cabrera, ha hecho un llamado urgente a los padres de familia para que eviten que sus hijos ingresen a los cuerpos de agua. Este exhorto surge a ra\u00edz de los recientes acontecimientos en el R\u00edo Nazas, donde lamentablemente ha perdido la vida un joven de 20 a\u00f1os originario de Torre\u00f3n, Coahuila, y se ha encontrado un cuerpo flotante en el canal San Jacinto en recientes d\u00edas.<\/p>\n\n\n\n<p>El Alcalde enfatiz\u00f3 la importancia de que los ciudadanos comprendan la gravedad de introducirse en el R\u00edo Nazas y los canales de riego, como los de Tlahualilo y Sacramento, que han sido escenarios de accidentes que ponen en peligro la vida y la integridad de las personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ha hecho un llamado urgente a los padres de familia 06 de julio de 2023. Lerdo, Durango.- El Alcalde de Lerdo, Homero Mart\u00ednez Cabrera, ha hecho un llamado urgente a los padres de familia para que eviten que sus hijos ingresen a los cuerpos de agua. Este exhorto surge a ra\u00edz de los recientes acontecimientos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=518"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/518\/revisions"}],"predecessor-version":[{"id":520,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/518\/revisions\/520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/519"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}