{"id":4387,"date":"2025-12-01T07:20:00","date_gmt":"2025-12-01T07:20:00","guid":{"rendered":"https:\/\/lagumex.mx\/index\/?p=4387"},"modified":"2025-12-02T19:21:57","modified_gmt":"2025-12-02T19:21:57","slug":"presentan-en-gomez-palacio-el-plan-municipal-de-desarrollo-2025-2028","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/gomez-palacio\/presentan-en-gomez-palacio-el-plan-municipal-de-desarrollo-2025-2028\/","title":{"rendered":"Presentan en G\u00f3mez Palacio el Plan Municipal de Desarrollo 2025\u20132028"},"content":{"rendered":"\n<p>01 de diciembre de 2025.- En un acto celebrado este lunes, la alcaldesa de G\u00f3mez Palacio, Betzab\u00e9 Mart\u00ednez Arango, dio a conocer el que ser\u00e1 el documento rector de su administraci\u00f3n para el periodo 2025\u20132028. Acompa\u00f1ada por representantes empresariales, productores del campo, acad\u00e9micos y ciudadanos de distintos sectores, la presidenta municipal deline\u00f3 los ejes que, asegur\u00f3, definir\u00e1n el rumbo de su gobierno. <\/p>\n\n\n\n<p>El primero es el combate frontal a la corrupci\u00f3n, donde reiter\u00f3 que no habr\u00e1 margen para actos que vulneren la confianza p\u00fablica, independientemente del cargo o trayectoria de los servidores involucrados.<\/p>\n\n\n\n<pre id=\"notaB2\" class=\"wp-block-preformatted\"><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>01 de diciembre de 2025.- En un acto celebrado este lunes, la alcaldesa de G\u00f3mez Palacio, Betzab\u00e9 Mart\u00ednez Arango, dio a conocer el que ser\u00e1 el documento rector de su administraci\u00f3n para el periodo 2025\u20132028. Acompa\u00f1ada por representantes empresariales, productores del campo, acad\u00e9micos y ciudadanos de distintos sectores, la presidenta municipal deline\u00f3 los ejes que,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4388,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-4387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gomez-palacio"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=4387"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4387\/revisions"}],"predecessor-version":[{"id":4389,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4387\/revisions\/4389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/4388"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=4387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=4387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=4387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}