{"id":4384,"date":"2025-12-01T07:12:00","date_gmt":"2025-12-01T07:12:00","guid":{"rendered":"https:\/\/lagumex.mx\/index\/?p=4384"},"modified":"2025-12-02T19:14:02","modified_gmt":"2025-12-02T19:14:02","slug":"inauguran-manolo-y-paola-villamagia-2025","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/uncategorized\/uac\/uac-uac\/coahuila-coahuila\/inauguran-manolo-y-paola-villamagia-2025\/","title":{"rendered":"Inauguran Manolo y Paola Villamagia 2025"},"content":{"rendered":"\n<p>01 de diciembre de 2025.- Desde M\u00fazquiz, el gobernador Manolo Jim\u00e9nez y su esposa Paola Rodr\u00edguez L\u00f3pez, presidenta honoraria de Inspira Coahuila, acompa\u00f1ados por sus hijos y por la alcaldesa Laura Patricia Jim\u00e9nez, encendieron el pino Monumental de Villamagia, con lo que se da inicio a los festejos de la temporada navide\u00f1a en la entidad.<\/p>\n\n\n\n<p>El encendido de Villamagia se realiz\u00f3 de manera simult\u00e1nea en los municipios de M\u00fazquiz, Torre\u00f3n, Monclova, Parras de la Fuente y Saltillo, y estar\u00e1n hasta el 6 de enero de 2026.<\/p>\n\n\n\n<p>Villamagia es un proyecto impulsado desde la oficina Inspira Coahuila pensado en fortalecer el tejido social y familiar, ofreciendo a todos y todas las coahuilenses un espacio de convivencia, resaltar los valores que se promueven en las festividades decembrinas y que sus visitantes disfruten en una villa con juguetes mexicanos, figuras gigantes y eventos propios de la temporada.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez destac\u00f3 que al igual que se est\u00e1 haciendo en M\u00fazquiz, Villamagia se est\u00e1 inaugurando por tercer a\u00f1o en las plazas principales de algunos municipios de diferentes regiones del Estado.<\/p>\n\n\n\n<p>Mencion\u00f3 que estos son espacios de convivencia y recreaci\u00f3n familiar, que se pueden disfrutar en completa paz y tranquilidad.<\/p>\n\n\n\n<p>Reconoci\u00f3 el gran trabajo y esfuerzo que se realiza desde la oficina Inspira, que dirige su esposa Paola Rodr\u00edguez, para coordinar todas las actividades en todas las sedes de este exitoso proyecto que se puso en marcha desde la primera temporada decembrina de su administraci\u00f3n.<\/p>\n\n\n\n<p>Dese\u00f3 a todas y todos los coahuilenses una Feliz Navidad y un a\u00f1o 2026 lleno de \u00e9xitos, y les pidi\u00f3 seguir trabajando en unidad para continuar consolidando a Coahuila como el mejor estado para vivir con nuestras familias.<\/p>\n\n\n\n<p>Villamagia est\u00e1 compuesta por \u00e1rboles navide\u00f1os de m\u00e1s de 20 metros de altura; figuras gigantes de algunos de los juguetes tradicionales mexicanos como el trompo, el balero, el caballito y el soldado de madera, entre otros.<\/p>\n\n\n\n<p>Adem\u00e1s, participan grupos locales en diversas actividades y espect\u00e1culos propias de la temporada.<\/p>\n\n\n\n<p>En las dos pasadas ediciones se registraron m\u00e1s de tres millones de visitas en las diferentes sedes.<\/p>\n\n\n\n<p>En este evento acompa\u00f1aron al gobernador, adem\u00e1s, Blas Jos\u00e9 Flores Gonz\u00e1lez, jefe de Gabinete y Proyectos Estrat\u00e9gicos; H\u00e9ctor Miguel Garc\u00eda Falc\u00f3n, esposo de la alcaldesa de M\u00fazquiz; Francisco Tob\u00edas Hern\u00e1ndez, subsecretario de Gobierno en la regi\u00f3n Carbon\u00edfera; Federico Quintanilla Riojas, coordinador regional de Mejora en la regi\u00f3n Carbon\u00edfera; Jes\u00fas Guerrero Garc\u00eda, coordinador municipal de Mejora. INAUGURAN MANOLO Y PAOLA VILLAMAGIA 2025<\/p>\n\n\n\n<p>Desde M\u00fazquiz y de manera simult\u00e1nea en todas las sedes de las diferentes regiones, inician los festejos navide\u00f1os en Coahuila<\/p>\n\n\n\n<p>Melchor M\u00fazquiz, Coahuila de Zaragoza; a 30 de noviembre de 2025.- Desde M\u00fazquiz, el gobernador Manolo Jim\u00e9nez y su esposa Paola Rodr\u00edguez L\u00f3pez, presidenta honoraria de Inspira Coahuila, acompa\u00f1ados por sus hijos y por la alcaldesa Laura Patricia Jim\u00e9nez, encendieron el pino Monumental de Villamagia, con lo que se da inicio a los festejos de la temporada navide\u00f1a en la entidad.<\/p>\n\n\n\n<p>El encendido de Villamagia se realiz\u00f3 de manera simult\u00e1nea en los municipios de M\u00fazquiz, Torre\u00f3n, Monclova, Parras de la Fuente y Saltillo, y estar\u00e1n hasta el 6 de enero de 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>01 de diciembre de 2025.- Desde M\u00fazquiz, el gobernador Manolo Jim\u00e9nez y su esposa Paola Rodr\u00edguez L\u00f3pez, presidenta honoraria de Inspira Coahuila, acompa\u00f1ados por sus hijos y por la alcaldesa Laura Patricia Jim\u00e9nez, encendieron el pino Monumental de Villamagia, con lo que se da inicio a los festejos de la temporada navide\u00f1a en la entidad&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":4385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila-coahuila"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=4384"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4384\/revisions"}],"predecessor-version":[{"id":4386,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4384\/revisions\/4386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/4385"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=4384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=4384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=4384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}