{"id":4275,"date":"2025-10-13T19:29:53","date_gmt":"2025-10-13T19:29:53","guid":{"rendered":"https:\/\/lagumex.mx\/index\/?p=4275"},"modified":"2025-10-30T19:30:57","modified_gmt":"2025-10-30T19:30:57","slug":"buscan-garantizar-la-calidad-del-agua-en-lerdo-con-analisis-periodicos-del-liquido","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/buscan-garantizar-la-calidad-del-agua-en-lerdo-con-analisis-periodicos-del-liquido\/","title":{"rendered":"Buscan garantizar la calidad del agua en Lerdo con an\u00e1lisis peri\u00f3dicos del l\u00edquido"},"content":{"rendered":"\n<p>13 de octubre de 2025.- Con la finalidad de garantizar el abasto y la calidad de agua potable que llega hasta las llaves de cada domicilio en Lerdo, el Municipio y el Gobierno del Estado podr\u00e1n en marcha el mantenimiento de pozos de forma peri\u00f3dica as\u00ed como la toma de muestras constantes para garantizar la buena calidad.La alcaldesa, Susy Torrecillas record\u00f3 que el pasado s\u00e1bado realiz\u00f3 una supervisi\u00f3n del mantenimiento que sufri\u00f3 el pozo abastecedor de la comunidad de El Huarache, trabajos que se habr\u00e1n de replicar con el resto. Adem\u00e1s, adelant\u00f3 que en la visita del mandatario, se habr\u00e1 de poner en marcha la toma de muestras y an\u00e1lisis para verificar la calidad del agua, y que en caso necesario, invertir en la colocaci\u00f3n de filtros sobre todo en el \u00e1rea rural.<\/p>\n\n\n\n<p>\u201cVamos a estar tomando muestras y an\u00e1lisis de la calidad del agua que estamos entregando para que si hay que invertir en otros filtros, para que pueda ir todav\u00eda m\u00e1s saludable, lo estaremos haciendo \u2026 que todos sepan que estamos atendiendo ello y que yo no le tengo miedo a la queja, la sugerencia, para eso estuve toque y toque puertas, as\u00ed que lo que estoy haciendo es fortalecer mi equipo de trabajo para que todos juntos salgamos a trabajar y dar respuesta a la gente\u201d, dijo la alcaldesa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>13 de octubre de 2025.- Con la finalidad de garantizar el abasto y la calidad de agua potable que llega hasta las llaves de cada domicilio en Lerdo, el Municipio y el Gobierno del Estado podr\u00e1n en marcha el mantenimiento de pozos de forma peri\u00f3dica as\u00ed como la toma de muestras constantes para garantizar la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=4275"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4275\/revisions"}],"predecessor-version":[{"id":4277,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4275\/revisions\/4277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/4276"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=4275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=4275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=4275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}