{"id":4211,"date":"2025-10-08T05:28:00","date_gmt":"2025-10-08T05:28:00","guid":{"rendered":"https:\/\/lagumex.mx\/index\/?p=4211"},"modified":"2025-10-08T17:29:09","modified_gmt":"2025-10-08T17:29:09","slug":"avanza-en-comision-reformas-para-que-menores-no-accedan-a-vapeadores-y-drogas-sinteticas","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/uncategorized\/torreon\/avanza-en-comision-reformas-para-que-menores-no-accedan-a-vapeadores-y-drogas-sinteticas\/","title":{"rendered":"Avanza en Comisi\u00f3n reformas para que menores no accedan a vapeadores y drogas sint\u00e9ticas"},"content":{"rendered":"\n<p>08 de octubre de 2025.- La Comisi\u00f3n de Puntos Constitucionales del Congreso del Estado aprob\u00f3 tres dict\u00e1menes de reformas, uno de ellos, en materia de protecci\u00f3n a menores, que busca prohibir la facilitaci\u00f3n de cigarrillos electr\u00f3nicos, vapeadores, fentanilo y otras drogas sint\u00e9ticas a personas menores de edad.<\/p>\n\n\n\n<p>Asimismo, en la Comisi\u00f3n que presiden el diputado Bernab\u00e9 Aguilar Carrillo, los otros dos dict\u00e1menes que se avalaron ser\u00e1n enviados al Congreso de la Uni\u00f3n para su an\u00e1lisis y eventual armonizaci\u00f3n.<\/p>\n\n\n\n<p>Uno de ellos, plantea que las personas que realicen su servicio social profesional tengan derecho a recibir una retribuci\u00f3n no contributiva por parte del Estado; y el segundo busca garantizar el cumplimiento del Plan de Justicia para los Pueblos Originarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>08 de octubre de 2025.- La Comisi\u00f3n de Puntos Constitucionales del Congreso del Estado aprob\u00f3 tres dict\u00e1menes de reformas, uno de ellos, en materia de protecci\u00f3n a menores, que busca prohibir la facilitaci\u00f3n de cigarrillos electr\u00f3nicos, vapeadores, fentanilo y otras drogas sint\u00e9ticas a personas menores de edad. Asimismo, en la Comisi\u00f3n que presiden el diputado&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-torreon"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=4211"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4211\/revisions"}],"predecessor-version":[{"id":4213,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/4211\/revisions\/4213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/4212"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=4211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=4211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=4211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}