{"id":417,"date":"2023-06-15T18:20:00","date_gmt":"2023-06-15T18:20:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=417"},"modified":"2023-07-01T18:22:50","modified_gmt":"2023-07-01T18:22:50","slug":"copladem-aprueba-obras-a-realizar-con-recursos-del-credito-de-banobras-en-lerdo","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/copladem-aprueba-obras-a-realizar-con-recursos-del-credito-de-banobras-en-lerdo\/","title":{"rendered":"Copladem aprueba obras a realizar con recursos del cr\u00e9dito de Banobras en Lerdo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Esteban Villegas confirm\u00f3 que el Gobierno del Estado realizar\u00e1 una inversi\u00f3n de 30 millones este a\u00f1o en Lerdo<\/h2>\n\n\n\n<p>15 de junio de 2023.El alcalde, Homero Mart\u00ednez Cabrera, presidi\u00f3 la sesi\u00f3n del Comit\u00e9 de Planeaci\u00f3n para el Desarrollo Municipal (Copladem), donde se aprob\u00f3 por unanimidad las obras a ejecutarse con el recurso obtenido del anticipo de prestaciones por parte del Banco Nacional de Obras y Servicios P\u00fablicos (Banobras), con un monto de 19.2 millones de pesos, y un total de 27 acciones a realizar en materia de agua potable, drenaje, electrificaci\u00f3n y pavimentaci\u00f3n.<\/p>\n\n\n\n<p>El edil estuvo acompa\u00f1ado del secretario del comit\u00e9, Alberto Escobedo; el director de Desarrollo Social, Daniel Salazar; el titular de Obras P\u00fablicas, Antonio S\u00e1nchez; el secretario del Ayuntamiento, Eduardo Lara; el tesorero municipal, Juan Moreno; el contralor, Alonzo Villalobos; sociedad civil, representantes rurales, empresarios; y regidores en car\u00e1cter de invitados especiales.<\/p>\n\n\n\n<p>El alcalde record\u00f3 que fue el pasado a\u00f1o en el mes de septiembre, cuando se aprob\u00f3 por el Cabildo solicitar un adelanto de los recursos que el municipio recibe en el trienio del Fondo de Infraestructura Social Municipal (FISM), petici\u00f3n que fue evaluada por Banobras para su factibilidad en el financiamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esteban Villegas confirm\u00f3 que el Gobierno del Estado realizar\u00e1 una inversi\u00f3n de 30 millones este a\u00f1o en Lerdo 15 de junio de 2023.El alcalde, Homero Mart\u00ednez Cabrera, presidi\u00f3 la sesi\u00f3n del Comit\u00e9 de Planeaci\u00f3n para el Desarrollo Municipal (Copladem), donde se aprob\u00f3 por unanimidad las obras a ejecutarse con el recurso obtenido del anticipo de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=417"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/417\/revisions"}],"predecessor-version":[{"id":419,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/417\/revisions\/419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/418"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}