{"id":3936,"date":"2025-03-18T02:08:19","date_gmt":"2025-03-18T02:08:19","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=3936"},"modified":"2025-03-29T02:09:26","modified_gmt":"2025-03-29T02:09:26","slug":"esteban-y-tono-entregan-tres-nuevas-escuelas-en-durango-mejoran-la-infraestructura-educativa-y-fortalecen-el-desarrollo-academico","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/esteban-y-tono-entregan-tres-nuevas-escuelas-en-durango-mejoran-la-infraestructura-educativa-y-fortalecen-el-desarrollo-academico\/","title":{"rendered":"Esteban y To\u00f1o entregan tres nuevas escuelas en Durango, mejoran la infraestructura educativa y fortalecen el desarrollo acad\u00e9mico"},"content":{"rendered":"\n<p>18 de marzo de 205.- M\u00e1s ni\u00f1as, ni\u00f1os y j\u00f3venes acceden a una educaci\u00f3n de calidad en espacios dignos y seguros con la creaci\u00f3n de tres nuevas escuelas en Villas del Manantial. Con una inversi\u00f3n superior a los 18 millones de pesos, el gobernador Esteban Villegas Villarreal y el alcalde To\u00f1o Ochoa entregaron el jard\u00edn de ni\u00f1os Francisco Villa, la primaria Pedro \u00c1vila Nev\u00e1rez y la secundaria t\u00e9cnica 86, as\u00ed reafirman su compromiso con la educaci\u00f3n y brindan\u00a0 de mejores oportunidades para el desarrollo acad\u00e9mico de la ni\u00f1ez y juventud duranguense.<\/p>\n\n\n\n<p>El gobernador destac\u00f3 que esta zona de la ciudad renace con infraestructura renovada, lo que marca un antes y un despu\u00e9s para los alumnos. Resalt\u00f3 que en una segunda etapa, se contempla la instalaci\u00f3n de aulas digitales, un avance significativo que permitir\u00e1 acceder a recursos tecnol\u00f3gicos de vanguardia, que mejorar\u00e1n el aprendizaje y preparaci\u00f3n para los retos del futuro. Este esfuerzo, dijo, no solo fortalece la calidad educativa, sino que abre puertas a nuevas oportunidades para el desarrollo acad\u00e9mico y personal de los estudiantes.<\/p>\n\n\n\n<p>Durante el evento, Villegas Villarreal, enmarc\u00f3 que Durango es el \u00fanico estado del pa\u00eds, que cuenta con becas, uniformes y \u00fatiles escolares gratuitos, comedores con desayunos calientes, as\u00ed como programas innovadores en tecnolog\u00eda y carreras t\u00e9cnicas de nueva creaci\u00f3n que han servido de modelo a nivel nacional.<\/p>\n\n\n\n<p>Por su parte, el presidente municipal To\u00f1o Ochoa destac\u00f3 que estas nuevas instalaciones ofrecer\u00e1n a los ni\u00f1os y j\u00f3venes de la zona una educaci\u00f3n de alta calidad, permiti\u00e9ndoles desarrollarse en un entorno moderno y seguro. \u201cLa educaci\u00f3n es la clave para alcanzar m\u00e1s sue\u00f1os y construir el futuro de Durango\u201d, enfatiz\u00f3 el edil, reafirmando el compromiso del gobierno municipal con el bienestar y progreso de la comunidad. Gracias a estos espacios, los estudiantes podr\u00e1n contar con un entorno adecuado para su aprendizaje y crecimiento integral, brindando igualdad de oportunidades para todos.<\/p>\n\n\n\n<p>El secretario de Educaci\u00f3n, Guillermo Adame Calder\u00f3n, resalt\u00f3 el entusiasmo del alumnado al contar con instalaciones dignas, se\u00f1alando que estas nuevas escuelas responden a las necesidades del crecimiento urbano y mejoran la infraestructura educativa. Record\u00f3 que, durante la administraci\u00f3n de Esteban Villegas, se reemplazaron las escuelas de cart\u00f3n por aulas de calidad, garantizando un desarrollo saludable y seguro para la ni\u00f1ez.<\/p>\n\n\n\n<p>El diputado local, Noel Fern\u00e1ndez, reiter\u00f3 su compromiso de continuar trabajando desde el Congreso para mejorar la infraestructura en la zona. Explic\u00f3 que se est\u00e1n implementando proyectos que incluyen la mejora de servicios b\u00e1sicos, como la electricidad. Estas acciones brindar\u00e1n a los estudiantes un entorno adecuado para su desarrollo acad\u00e9mico y profesional, ampliando las oportunidades para todos.<\/p>\n\n\n\n<p>El menor Gael Gurrola Medina, en un emotivo momento, agradeci\u00f3 a las autoridades por las nuevas escuelas, que brindan igualdad de oportunidades. \u201cGracias a estos espacios, podemos so\u00f1ar con un futuro mejor\u201d, expres\u00f3.<\/p>\n\n\n\n<p>En este evento tambi\u00e9n estuvieron Emmanuel del Palacio Sicsik, director del Instituto para la Infraestructura F\u00edsica Educativa del Estado (INIFEED), Carlos Mart\u00ednez Espinoza, presidente de la Asociaci\u00f3n Estatal de Padres de Familia, como los directores y acad\u00e9micos del jard\u00edn de Ni\u00f1os, la primaria y la Telesecundaria, alumnado y padres de familia, quienes constataron que, con la creaci\u00f3n de estas escuelas, los ni\u00f1os y j\u00f3venes de la zona tienen ahora la oportunidad de acceder a una educaci\u00f3n de calidad, lo que les permitir\u00e1 un desarrollo m\u00e1s completo y mayores oportunidades en el futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>18 de marzo de 205.- M\u00e1s ni\u00f1as, ni\u00f1os y j\u00f3venes acceden a una educaci\u00f3n de calidad en espacios dignos y seguros con la creaci\u00f3n de tres nuevas escuelas en Villas del Manantial. Con una inversi\u00f3n superior a los 18 millones de pesos, el gobernador Esteban Villegas Villarreal y el alcalde To\u00f1o Ochoa entregaron el jard\u00edn&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=3936"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3936\/revisions"}],"predecessor-version":[{"id":3938,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3936\/revisions\/3938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/3937"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=3936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=3936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=3936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}