{"id":3846,"date":"2025-02-12T22:50:00","date_gmt":"2025-02-12T22:50:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=3846"},"modified":"2025-03-28T22:52:06","modified_gmt":"2025-03-28T22:52:06","slug":"con-esteban-y-homero-estrenan-cancha-domo-y-otras-obras-en-sapioriz","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/con-esteban-y-homero-estrenan-cancha-domo-y-otras-obras-en-sapioriz\/","title":{"rendered":"Con Esteban y Homero, estrenan cancha, domo y otras obras en Sapioriz"},"content":{"rendered":"\n<p>12 de febrero de 2025.- Con una inversi\u00f3n de 12 millones de pesos en obras de salud, infraestructura hidr\u00e1ulica, pavimentaci\u00f3n y espacios deportivos, el gobernador Esteban Villegas Villarreal reafirm\u00f3 su compromiso con los habitantes de Lerdo, esto al visitar Sapioriz e inaugurar una nueva cancha con domo, adem\u00e1s de una calle rehabilitada y mejoras para el c\u00e1rcamo del lugar.<\/p>\n\n\n\n<p>El Mandatario destac\u00f3 que estas acciones responden a solicitudes prioritarias de la comunidad, que brindan un espacio adecuado para el deporte y la convivencia. Asimismo, subray\u00f3 el apoyo continuo en educaci\u00f3n y vivienda, as\u00ed como los programas del DIF Estatal, que incluyen cirug\u00edas y aparatos asistenciales.<\/p>\n\n\n\n<p>\u201cLleg\u00f3 la hora de Lerdo y Sapioriz. Vamos a seguir trabajando en equipo\u201d, afirm\u00f3 Villegas Villarreal quien reconoci\u00f3&nbsp; la colaboraci\u00f3n de alcaldes y diputados para transformar el presupuesto en obras de calidad.<\/p>\n\n\n\n<p>Por su parte, el presidente municipal de Lerdo, Homero Mart\u00ednez Cabrera, destac\u00f3 la importancia de estas obras y enumer\u00f3 los nuevos proyectos en beneficio de la ciudadan\u00eda, como la red el\u00e9ctrica y la cancha de usos m\u00faltiples; \u201cvemos el apoyo y respaldo de Esteban Villegas, quien apuesta por el desarrollo de Lerdo\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El director de Obras P\u00fablicas, Juan Antonio L\u00f3pez S\u00e1nchez, explic\u00f3 que la nueva infraestructura deportiva responde a una demanda de la comunidad, mientras que la rehabilitaci\u00f3n del c\u00e1rcamo ayudar\u00e1 a resolver el problema de aguas negras.<\/p>\n\n\n\n<p>Finalmente, el jefe de cuartel, Jos\u00e9 \u00c1ngel Puentes, agradeci\u00f3 a las autoridades por la construcci\u00f3n de la cancha, cuyo impacto es positivo en ni\u00f1os, j\u00f3venes y adultos al fomentar el deporte y la sana convivencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>12 de febrero de 2025.- Con una inversi\u00f3n de 12 millones de pesos en obras de salud, infraestructura hidr\u00e1ulica, pavimentaci\u00f3n y espacios deportivos, el gobernador Esteban Villegas Villarreal reafirm\u00f3 su compromiso con los habitantes de Lerdo, esto al visitar Sapioriz e inaugurar una nueva cancha con domo, adem\u00e1s de una calle rehabilitada y mejoras para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=3846"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3846\/revisions"}],"predecessor-version":[{"id":3848,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3846\/revisions\/3848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/3847"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=3846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=3846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=3846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}