{"id":3468,"date":"2024-12-17T19:22:19","date_gmt":"2024-12-17T19:22:19","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=3468"},"modified":"2024-12-27T19:23:27","modified_gmt":"2024-12-27T19:23:27","slug":"ninas-y-ninos-de-casa-hogar-disfrutaron-de-villancicos-juegos-y-bailes-con-posadas-que-les-llevaron-marisol-y-esteban","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/ninas-y-ninos-de-casa-hogar-disfrutaron-de-villancicos-juegos-y-bailes-con-posadas-que-les-llevaron-marisol-y-esteban\/","title":{"rendered":"Ni\u00f1as y ni\u00f1os de Casa Hogar disfrutaron de villancicos, juegos y bailes, con posadas que les llevaron Marisol y Esteban"},"content":{"rendered":"\n<p>17 de diciembre de 2024.- Este es un d\u00eda muy especial, somos afortunados de poder estar aqu\u00ed con las ni\u00f1as y ni\u00f1os de este hermoso lugar, expresaron la presidenta del DIF Estatal, Marisol Rosso y el gobernador Esteban Villegas Villarreal, al celebrar la tradicional posada de Casa Hogar y Centro Mi Casa con villancicos, pi\u00f1atas, juegos y regalos.<\/p>\n\n\n\n<p>El Ejecutivo Estatal record\u00f3 que este convivio que se lleva a\u00f1o tras a\u00f1o, en el que los duranguenses se unen a apadrinar a los ni\u00f1os y adolescentes de la Casa Hogar, es con el fin de que puedan disfrutar de las fiestas decembrinas en un ambiente de mucho amor y fomentando los valores y las tradiciones.<\/p>\n\n\n\n<p>\u201cMi esposo, el Gobernador y quien es el pap\u00e1 de todos ustedes, mis hermosos peque\u00f1os, est\u00e1 siempre al pendiente trabajando desde el coraz\u00f3n\u201d, dijo Rosso Rivera, al reconocer su labor de hacer una gran familia, con mucho amor para los ni\u00f1os y sobretodo, en un ejercicio de proteger y garantizar sus derechos.<\/p>\n\n\n\n<p>De igual forma la presidenta del DIF Estatal, comparti\u00f3 la alegr\u00eda de este festejo con cada uno de los menores, \u201cgracias por esa energ\u00eda y amor que transmiten, por ser el motor de nuestras sonrisas\u201d, expres\u00f3 tras agradecer tambi\u00e9n a los voluntarios y colaboradores por su tiempo y dedicaci\u00f3n, de estar siempre con el mejor \u00e1nimo para hacer que Casa Hogar sea mejor cada d\u00eda.<\/p>\n\n\n\n<p>La procuradora de Protecci\u00f3n de Ni\u00f1as, Ni\u00f1os y Adolescentes, Laura Cecilia Rodr\u00edguez Franco, dijo que es de reconocer estos momentos que se vuelven m\u00e1gicos para cada ni\u00f1o de Casa Hogar y Centro Mi Casa, al brindarles ese cari\u00f1o y una tarde de alegr\u00edas, juegos y regalos.<\/p>\n\n\n\n<p>En esta convivencia, Villegas Villarreal y su esposa Marisol, compartieron una tarde de posadas, bailes y mucha alegr\u00eda para los ni\u00f1os con personajes alusivos a la Navidad junto a integrantes del Gabinete Estatal, empresarios y sociedad civil, adem\u00e1s, los peque\u00f1os y adolescentes pudieron disfrutar tambi\u00e9n de brincolines y juegos infantiles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>17 de diciembre de 2024.- Este es un d\u00eda muy especial, somos afortunados de poder estar aqu\u00ed con las ni\u00f1as y ni\u00f1os de este hermoso lugar, expresaron la presidenta del DIF Estatal, Marisol Rosso y el gobernador Esteban Villegas Villarreal, al celebrar la tradicional posada de Casa Hogar y Centro Mi Casa con villancicos, pi\u00f1atas,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=3468"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3468\/revisions"}],"predecessor-version":[{"id":3470,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3468\/revisions\/3470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/3469"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=3468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=3468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=3468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}