{"id":3438,"date":"2024-12-02T16:12:59","date_gmt":"2024-12-02T16:12:59","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=3438"},"modified":"2024-12-13T16:14:32","modified_gmt":"2024-12-13T16:14:32","slug":"vamos-por-un-gobierno-mas-eficiente-sin-organismos-autonomos-alejandro-mata","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/uncategorized\/congreso-de-durango\/vamos-por-un-gobierno-mas-eficiente-sin-organismos-autonomos-alejandro-mata\/","title":{"rendered":"Vamos por un gobierno m\u00e1s eficiente sin organismos aut\u00f3nomos: Alejandro Mata"},"content":{"rendered":"\n<p>02 de diciembre de 2024.- La eliminaci\u00f3n de los organismos aut\u00f3nomos representa un cambio de r\u00e9gimen necesario para la eficiencia gubernamental, lo cual permite tener un gobierno m\u00e1s eficiente, \u00e1gil y transparente, se\u00f1al\u00f3 el diputado Alejandro Mata Valadez al razonar su voto a favor de la minuta en materia de simplificaci\u00f3n org\u00e1nica.<\/p>\n\n\n\n<p>\u201cEn varios pa\u00edses no existen organismos aut\u00f3nomos; esto es parte de un reacomodo, un cambio estructural para que el gobierno sea m\u00e1s eficiente\u201d, afirm\u00f3 Mata Valadez, subrayando que muchos de estos organismos solo fueron creados para despresurizar conflictos sociales, sin lograr un impacto real en su desempe\u00f1o.<\/p>\n\n\n\n<p>Puso como ejemplo que en lo personal present\u00f3 m\u00e1s de mil 500 solicitudes en el INAI, de las cuales se clasificaban como informaci\u00f3n sensible y otras muchas se perd\u00edan en el proceso.<\/p>\n\n\n\n<p>A nombre del Grupo Parlamentario de Morena, el legislador tambi\u00e9n enfatiz\u00f3 que el objetivo principal debe ser construir una mejor administraci\u00f3n p\u00fablica, como sucede en Estados Unidos de Am\u00e9rica, donde los encargados de cada dependencia sean m\u00e1s eficientes.<br>\u201cVamos a luchar por adelgazar la n\u00f3mina, optimizar los recursos y responder al llamado del pueblo de M\u00e9xico\u201d, concluy\u00f3 el legislador lagunero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>02 de diciembre de 2024.- La eliminaci\u00f3n de los organismos aut\u00f3nomos representa un cambio de r\u00e9gimen necesario para la eficiencia gubernamental, lo cual permite tener un gobierno m\u00e1s eficiente, \u00e1gil y transparente, se\u00f1al\u00f3 el diputado Alejandro Mata Valadez al razonar su voto a favor de la minuta en materia de simplificaci\u00f3n org\u00e1nica. \u201cEn varios pa\u00edses&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-3438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-congreso-de-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=3438"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3438\/revisions"}],"predecessor-version":[{"id":3440,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3438\/revisions\/3440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/3439"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=3438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=3438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=3438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}