{"id":3310,"date":"2024-11-21T22:03:00","date_gmt":"2024-11-21T22:03:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=3310"},"modified":"2024-12-02T22:04:04","modified_gmt":"2024-12-02T22:04:04","slug":"confirmado-va-construccion-de-presa-tunal-ii-dentro-del-plan-nacional-hidrico-2025-se-incluye-dentro-de-los-proyectos-estrategicos-del-gobierno-de-mexico","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/confirmado-va-construccion-de-presa-tunal-ii-dentro-del-plan-nacional-hidrico-2025-se-incluye-dentro-de-los-proyectos-estrategicos-del-gobierno-de-mexico\/","title":{"rendered":"Confirmado, va construcci\u00f3n de presa Tunal II dentro del Plan Nacional H\u00eddrico 2025; se incluye dentro de los proyectos estrat\u00e9gicos del Gobierno de M\u00e9xico"},"content":{"rendered":"\n<p>21 de noviembre de 2024.- Gracias a las gestiones del gobernador Esteban Villegas Villarreal y la buena disposici\u00f3n de la presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, el Gobierno Federal oficializ\u00f3 para el 2025 la construcci\u00f3n de la Presa Tunal II dentro de los proyectos estrat\u00e9gicos para garantizar el acceso al agua como un derecho fundamental, tal como lo anunci\u00f3 el titular de la Comisi\u00f3n Nacional del Agua (Conagua), Efra\u00edn Morales L\u00f3pez, dentro de la conferencia matutina \u201cLa Ma\u00f1anera del Pueblo\u201d.<\/p>\n\n\n\n<p>Fue este mismo jueves cuando la presidenta de la Rep\u00fablica y el titular de Conagua dieron a conocer la realizaci\u00f3n de 16 obras de infraestructura h\u00eddrica de gran envergadura en todo el pa\u00eds. Estas se llevar\u00e1n a cabo tras una revisi\u00f3n detallada y contar\u00e1n con inversi\u00f3n conjunta entre los gobiernos estatales y federal.<\/p>\n\n\n\n<p>El Plan Nacional H\u00eddrico se basa en cuatro ejes: Pol\u00edtica h\u00eddrica y soberan\u00eda nacional; Mitigaci\u00f3n del impacto ambiental y adaptaci\u00f3n al cambio clim\u00e1tico; Justicia y acceso al agua y Gesti\u00f3n integral y transparente. En este el Gobierno de M\u00e9xico invertir\u00e1 20 mil millones de pesos en proyectos de agua, con lo que se garantiza el derecho del pueblo al vital l\u00edquido.<\/p>\n\n\n\n<p>La construcci\u00f3n de la Presa el Tunal II se oficializ\u00f3 ante los medios de comunicaci\u00f3n dentro de los proyectos prioritarios 2024-2030, as\u00ed como la continuaci\u00f3n de las redes troncales para el proyecto Agua Saludable entre Durango &#8211; Coahuila.<\/p>\n\n\n\n<p>Adem\u00e1s, se pondr\u00e1 en marcha un Programa Nacional de Tecnificaci\u00f3n (en el que va incluido Durango) y que beneficiar\u00e1 a m\u00e1s de 225 mil productores de riego, lo que se traducir\u00e1 en mayor producci\u00f3n de alimentos con menor uso de agua. Parte del l\u00edquido recuperado se destinar\u00e1 al consumo humano y la recarga de los mantos acu\u00edferos.<\/p>\n\n\n\n<p>Lo mismo la emisi\u00f3n de un decreto que facilitar\u00e1 la regularizaci\u00f3n de concesiones vencidas, siempre y cuando cumplan con la ley, al permitir acceso a cr\u00e9ditos, subsidios y programas.<\/p>\n\n\n\n<p>En este sentido, el gobernador de Durango, Esteban Villegas Villarreal inform\u00f3 que, durante el fin de semana pasado, el director de Conagua visit\u00f3 Durango para explicar que las reglas de operaci\u00f3n del Fondo de Aportaciones para la Infraestructura Social (FAIS) cambiar\u00e1n en el 2025. \u201cAhora, entre un 80 y 90 por ciento&nbsp; de estos recursos se destinar\u00e1n exclusivamente a obras de agua y drenaje, lo que permitir\u00e1 realizar numerosos proyectos hidr\u00e1ulicos en distintas regiones del estado que fortalecer\u00e1n el Plan Nacional H\u00eddrico\u201d.<\/p>\n\n\n\n<p>El Mandatario Estatal aplaudi\u00f3 estas acciones que permitir\u00e1n resolver los problemas de agua en diversos estados del pa\u00eds, incluidos los de Durango, que se beneficiar\u00e1 junto con otros 15 proyectos estrat\u00e9gicos. Con ello, se priorizan las necesidades de los duranguenses en materia agr\u00edcola, pecuaria, de industria y consumo humano; adem\u00e1s de traer otros beneficios como ser reguladora para evitar inundaciones, as\u00ed como dejar un seguro de vida por m\u00e1s de 50 a\u00f1os a las pr\u00f3ximas generaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>21 de noviembre de 2024.- Gracias a las gestiones del gobernador Esteban Villegas Villarreal y la buena disposici\u00f3n de la presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, el Gobierno Federal oficializ\u00f3 para el 2025 la construcci\u00f3n de la Presa Tunal II dentro de los proyectos estrat\u00e9gicos para garantizar el acceso al agua como un derecho fundamental,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=3310"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3310\/revisions"}],"predecessor-version":[{"id":3312,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3310\/revisions\/3312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/3311"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=3310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=3310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=3310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}