{"id":3136,"date":"2024-10-17T13:37:00","date_gmt":"2024-10-17T13:37:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=3136"},"modified":"2024-11-01T13:38:19","modified_gmt":"2024-11-01T13:38:19","slug":"renueva-gobierno-del-estado-su-data-center-generara-mayor-seguridad-rapidez-y-transparencia-en-tramites-ciudadanos-esteban-villegas","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/renueva-gobierno-del-estado-su-data-center-generara-mayor-seguridad-rapidez-y-transparencia-en-tramites-ciudadanos-esteban-villegas\/","title":{"rendered":"Renueva Gobierno del Estado su Data Center; generar\u00e1 mayor seguridad, rapidez y transparencia en tr\u00e1mites ciudadanos: Esteban Villegas"},"content":{"rendered":"\n<p>17 de octubre de 2024.-Adem\u00e1s se renovaron 3 mil 950 computadoras de oficinas; equipo sustituido ser\u00e1 donado a escuelas de zonas alejadas.<\/p>\n\n\n\n<p>Con tecnolog\u00eda moderna y de \u00faltima generaci\u00f3n, seguiremos brindando a los duranguenses servicios seguros, r\u00e1pidos y transparentes en sus tr\u00e1mites, afirm\u00f3 el gobernador Esteban Villegas Villarreal al renovar el Data Center e infraestructura de c\u00f3mputo del Gobierno del Estado, con una inversi\u00f3n de 340 millones de pesos.<\/p>\n\n\n\n<p>\u201cLas computadoras ya no serv\u00edan, ten\u00edan 12 a\u00f1os sin renovar los Data Center, y la tecnolog\u00eda va cambiando\u201d, expres\u00f3 Villegas Villarreal, al detallar que fueron adquiridos 3 mil 950 equipos de c\u00f3mputo de \u00faltima generaci\u00f3n, distribuidos entre computadoras de escritorio, port\u00e1tiles y estaciones m\u00e1s eficientes, lo que permitir\u00e1 que la gente realice tr\u00e1mites m\u00e1s r\u00e1pido, incluso desde su casa o celular, en cualquier municipio del estado.<\/p>\n\n\n\n<p>\u201cEstos equipos nos ayudar\u00e1n a que los duranguenses tengan plena confianza de que todos sus datos, propiedades y los impuestos que pagan se mantengan en un servidor de primer nivel. Es importante tener esta tecnolog\u00eda, ya que hay personas que se dedican a extorsionar a trav\u00e9s de medios digitales\u201d, apunt\u00f3 el Gobernador.<\/p>\n\n\n\n<p>Adelant\u00f3 que el equipo que se dejar\u00e1 de usar en el Gobierno del Estado, y que a\u00fan es funcional, ser\u00e1 donado a escuelas que necesitan acercar la tecnolog\u00eda, especialmente en zonas alejadas donde es necesario que los ni\u00f1os conozcan y comiencen a utilizar una computadora, ya que esto puede cambiarles la vida por completo.<\/p>\n\n\n\n<p>Esta actualizaci\u00f3n de equipamiento reducir\u00e1 los tiempos de respuesta y facilitar\u00e1 la digitalizaci\u00f3n de tr\u00e1mites en \u00e1reas clave como Recaudaci\u00f3n de Rentas, Seguridad P\u00fablica, Registro P\u00fablico de la Propiedad, Registro Civil, Catastro, Educaci\u00f3n y Mejora Regulatoria. Tambi\u00e9n se modernizar\u00e1 todo el equipo del C5.<\/p>\n\n\n\n<p>Por su parte, el titular de la Secretar\u00eda de Finanzas y Administraci\u00f3n, Franklin Corlay Aguilar, detall\u00f3 que era muy necesario en el Gobierno del Estado una transformaci\u00f3n digital, sobre todo para quienes trabajan en las ventanillas, a fin de que puedan tener acceso r\u00e1pido al servidor. Por ello, se gestion\u00f3 un financiamiento para dotar de nuevas computadoras a distintas oficinas, asegurando as\u00ed un servicio al 100&nbsp; por ciento.<\/p>\n\n\n\n<p>Esta modernizaci\u00f3n del Centro de Datos se traduce en una infraestructura de hiperconvergencia y m\u00e1s de 1 petabyte de capacidad de almacenamiento. Esta nueva tecnolog\u00eda ofrecer\u00e1 mayor seguridad y continuidad en los m\u00e1s de 70 sistemas que soportan las operaciones del gobierno estatal, incluyendo los sistemas de n\u00f3mina, pagos en l\u00ednea y portales de transparencia.<\/p>\n\n\n\n<p>Todo esto se lleva a cabo con la finalidad de brindar una atenci\u00f3n de calidad a los ciudadanos, as\u00ed como a las nuevas empresas que desean invertir en Durango, para que sus tr\u00e1mites no se retrasen y las inversiones lleguen pronto a la entidad. Este avance tecnol\u00f3gico representa un Gobierno eficiente y seguro para los duranguenses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>17 de octubre de 2024.-Adem\u00e1s se renovaron 3 mil 950 computadoras de oficinas; equipo sustituido ser\u00e1 donado a escuelas de zonas alejadas. Con tecnolog\u00eda moderna y de \u00faltima generaci\u00f3n, seguiremos brindando a los duranguenses servicios seguros, r\u00e1pidos y transparentes en sus tr\u00e1mites, afirm\u00f3 el gobernador Esteban Villegas Villarreal al renovar el Data Center e infraestructura&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=3136"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3136\/revisions"}],"predecessor-version":[{"id":3138,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/3136\/revisions\/3138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/3137"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=3136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=3136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=3136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}