{"id":2730,"date":"2024-08-03T18:28:59","date_gmt":"2024-08-03T18:28:59","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2730"},"modified":"2024-08-04T18:29:59","modified_gmt":"2024-08-04T18:29:59","slug":"atiende-servicios-publicos-alumbrado-en-boulevard-aleman","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/atiende-servicios-publicos-alumbrado-en-boulevard-aleman\/","title":{"rendered":"Atiende servicios p\u00fablicos alumbrado en Boulevard Alem\u00e1n"},"content":{"rendered":"\n<p>03 de agosto de 2024, Lerdo, Durango.- Esta semana, la direcci\u00f3n de Servicios P\u00fablicos llev\u00f3 a cabo una importante rehabilitaci\u00f3n\u00a0<strong>en el bulevar Miguel Alem\u00e1n<\/strong>. Se<strong>\u00a0instalaron luminarias tipo LED<\/strong>\u00a0de 100 watts, mejorando la iluminaci\u00f3n de esta vialidad clave y brindando mayor seguridad a los conductores.<\/p>\n\n\n\n<p><strong>Raymundo Hern\u00e1ndez Vicu\u00f1a, jefe del departamento de Alumbrado P\u00fablico<\/strong>, inform\u00f3 que estos trabajos fueron una instrucci\u00f3n directa del Alcalde, Homero Mart\u00ednez Cabrera, destacando la importancia de atender esta arteria vial.Hern\u00e1ndez Vicu\u00f1a tambi\u00e9n exhort\u00f3 a la ciudadan\u00eda a reportar luminarias en mal estado. Para ello, se ha puesto a disposici\u00f3n el<strong>\u00a0n\u00famero de WhatsApp 87 11 16 95 83<\/strong>, adem\u00e1s de poder acudir directamente a las oficinas de\u00a0<strong>Atenci\u00f3n Ciudadana y Servicios P\u00fablicos<\/strong>\u00a0en la Presidencia Municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>03 de agosto de 2024, Lerdo, Durango.- Esta semana, la direcci\u00f3n de Servicios P\u00fablicos llev\u00f3 a cabo una importante rehabilitaci\u00f3n\u00a0en el bulevar Miguel Alem\u00e1n. Se\u00a0instalaron luminarias tipo LED\u00a0de 100 watts, mejorando la iluminaci\u00f3n de esta vialidad clave y brindando mayor seguridad a los conductores. Raymundo Hern\u00e1ndez Vicu\u00f1a, jefe del departamento de Alumbrado P\u00fablico, inform\u00f3 que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2730"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2730\/revisions"}],"predecessor-version":[{"id":2732,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2730\/revisions\/2732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/2731"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}