{"id":2721,"date":"2024-08-04T06:23:00","date_gmt":"2024-08-04T06:23:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2721"},"modified":"2024-08-04T18:24:32","modified_gmt":"2024-08-04T18:24:32","slug":"escuelas-de-verano-que-impulsa-el-gobierno-estatal-es-una-oportunidad-formativa-para-los-ninos-duranguenses","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/escuelas-de-verano-que-impulsa-el-gobierno-estatal-es-una-oportunidad-formativa-para-los-ninos-duranguenses\/","title":{"rendered":"Escuelas de Verano, que impulsa el Gobierno Estatal, es una oportunidad formativa para los ni\u00f1os duranguenses"},"content":{"rendered":"\n<p>04 de agosto de 2024.-\u201cLa educaci\u00f3n es el motor de los pueblos, si la formaci\u00f3n de las nuevas generaciones est\u00e1 en \u00f3ptimas condiciones, el estado crecer\u00e1 en todos los sentidos\u201d, afirm\u00f3 el director de la escuela primaria \u201cInsurgentes\u201d, Juan Francisco Gonz\u00e1lez Retana, al presenciar el desarrollo del programa \u201cEscuela de Verano\u201d.<\/p>\n\n\n\n<p>El subsecretario de Servicios Educativos, Rolando Cruz Garc\u00eda, explic\u00f3 que estas actividades buscan fortalecer los aprendizajes de estudiantes de educaci\u00f3n b\u00e1sica, sobre todo de aquellos que no lograron los resultados \u00f3ptimos en la Prueba Estandarizada, realizada en el pasado mes de abril.<\/p>\n\n\n\n<p>Sin embargo, se busca tambi\u00e9n crear una red de apoyo escolar y que los padres de familia se involucren en el proceso formativo de los alumnos, con apoyo de directivos y docentes. Por lo tanto, en \u201cEscuela de Verano\u201d, los estudiantes realizar\u00e1n actividades acad\u00e9micas de la mano con disciplinas como el deporte, el arte y la cultura, durante tres semanas, del 22 de julio al 9 de agosto, en 50 escuelas de municipios como Durango, Santiago Papasquiaro, Canatl\u00e1n, Nuevo Ideal, entre otros.<\/p>\n\n\n\n<p>V\u00edctor Jes\u00fas Rodr\u00edguez Ch\u00e1vez, padre de familia, expres\u00f3 estar contento y con gratitud por que este programa se haya activado este verano; \u201cme agrada que lo hayan tra\u00eddo nuevamente, es de mucho apoyo a los padres de familia, especialmente para aquellos ni\u00f1os que se les complica alg\u00fan detalle; \u201cespero que este programa continu\u00e9 a\u00f1o con a\u00f1o\u201d.<\/p>\n\n\n\n<p>Por su parte, Claudia Ravelo, madre de familia de la escuela primaria \u201cFrancisco villa\u201d coment\u00f3 que es un gran apoyo; \u201cestuve buscando pasant\u00edas, pero son muy caras, es mejor que mi hija est\u00e9 con profesionales, con toda la confianza dejar a mi hija en un lugar seguro\u201d.<\/p>\n\n\n\n<p>Roc\u00edo Gonz\u00e1lez Retana, madre de familia, dijo que \u201clos chicos necesitan atenci\u00f3n, estar ocupados, dejan un ratito los m\u00f3viles, las tablets, para reconocer las capacidades y las habilidades que tienen\u201d.<\/p>\n\n\n\n<p>En este sentido, Blanca Emilia Reyes Ibarra, directora de Educaci\u00f3n B\u00e1sica B, destac\u00f3 que estas acciones, forman parte del programa educativo \u201cAprendiendo en vacaciones\u201d misma que se consolida este ciclo escolar como \u201cEscuela de Verano\u201d.<\/p>\n\n\n\n<p>\u201cEl objetivo, es trabajar con los alumnos durante tres semanas para que consoliden los aprendizajes que no alcanzaron a desarrollar en el grado que acaban de terminar\u201d, explic\u00f3.<\/p>\n\n\n\n<p>Justo Mart\u00ednez Carrillo, director de Educaci\u00f3n B\u00e1sica A, mencion\u00f3 que, para el desarrollo de este programa, se incentivar\u00e1 con 120 horas con valor a USICAMM a aquellos maestros que se sumen a \u201cEscuela de Verano\u201d. Reconoci\u00f3 el esfuerzo del personal docente, administrativo y padres de familia por su disposici\u00f3n para unirse a esta estrategia.<\/p>\n\n\n\n<p>&nbsp;\u201cEs una tarea noble para la comunidad educativa de Durango, un trabajo centrado, con un enfoque en la nueva escuela mexicana en desarrollar el pensamiento cr\u00edtico de los estudiantes por supuesto, y en el desarrollo de habilidades, conocimientos, actitudes y destrezas\u201d apunt\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>04 de agosto de 2024.-\u201cLa educaci\u00f3n es el motor de los pueblos, si la formaci\u00f3n de las nuevas generaciones est\u00e1 en \u00f3ptimas condiciones, el estado crecer\u00e1 en todos los sentidos\u201d, afirm\u00f3 el director de la escuela primaria \u201cInsurgentes\u201d, Juan Francisco Gonz\u00e1lez Retana, al presenciar el desarrollo del programa \u201cEscuela de Verano\u201d. El subsecretario de Servicios&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2721"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2721\/revisions"}],"predecessor-version":[{"id":2723,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2721\/revisions\/2723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/2722"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}