{"id":2602,"date":"2024-07-11T04:23:06","date_gmt":"2024-07-11T04:23:06","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2602"},"modified":"2024-07-23T04:24:51","modified_gmt":"2024-07-23T04:24:51","slug":"obras-y-acciones-del-gobierno-de-esteban-llegan-hasta-las-comunidades-indigenas-para-mejorar-su-calidad-de-vida","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/obras-y-acciones-del-gobierno-de-esteban-llegan-hasta-las-comunidades-indigenas-para-mejorar-su-calidad-de-vida\/","title":{"rendered":"Obras y acciones del Gobierno de Esteban llegan hasta las comunidades ind\u00edgenas para mejorar su calidad de vida"},"content":{"rendered":"\n<p>11 de julio de 2024.- Anunci\u00f3 que las Tarjetas Madre se priorizar\u00e1n en la zona ind\u00edgena y llegar\u00e1n a las mujeres trabajadoras.<\/p>\n\n\n\n<p>Para que las familias de las comunidades del Mezquital, cuenten con espacios seguros, puedan convivir sanamente y los estudiantes tengan lugares dignos, el gobernador Esteban Villegas entreg\u00f3 la construcci\u00f3n de la plaza c\u00edvica de la localidad Los Charcos, un comedor estudiantil, una cancha y un domo en el CECyTE, adem\u00e1s de apoyos de vivienda y m\u00e1s, compromisos que ten\u00eda con los habitantes y les cumpli\u00f3.<\/p>\n\n\n\n<p>All\u00ed mismo el Ejecutivo Estatal, anunci\u00f3 que hasta las zonas m\u00e1s alejadas como esta, llegar\u00e1n&nbsp; las Tarjetas Madre, programa que se detuvo por las pasadas elecciones, pero que ya se retom\u00f3, y la cual tendr\u00e1 prioridad en las comunidades ind\u00edgenas.<\/p>\n\n\n\n<p>En su visita a Los Charcos, el Mandatario Estatal record\u00f3 que como parte de la infraestructura hidr\u00e1ulica, en esta comunidad se entreg\u00f3 un sistema de agua potable y otros cuatro en diversas localidades, adem\u00e1s, en esta ocasi\u00f3n llev\u00f3 equipo para los elementos de Seguridad P\u00fablica, una patrulla, uniformes y botas t\u00e1cticas.<\/p>\n\n\n\n<p>En apoyos de vivienda, se distribuyeron 3 mil l\u00e1minas en todo el municipio, 2 mil boilers solares, as\u00ed como celdas de luz; 300 apoyos alimentarios, 650 tinacos, 125 cuartos adicionales; \u201cel presidente del Mezquital le est\u00e1 echando ganas, se nota el cambio despu\u00e9s de seis a\u00f1os que estuvo abandonado el municipio, en la zona ind\u00edgena, sus carreteras\u201d, expres\u00f3 Villegas Villarreal.<\/p>\n\n\n\n<p>Dio a conocer que para continuar con el trabajo, se llevar\u00e1 maquinaria para arreglar caminos y trabajen en conjunto con el alcalde a favor de los habitantes; \u201cel Mezquital tiene gobernador amigo, sobre todo aqu\u00ed con nuestros hermanos ind\u00edgenas\u201d, afirm\u00f3 al hacerse acompa\u00f1ar del&nbsp; diputado de Chihuahua, Omar Baz\u00e1n, quien reconoci\u00f3 el compromiso de Esteban por Durango.<\/p>\n\n\n\n<p>A nombre de los beneficiarios, la joven M\u00f3nica Esther Aguilar, de la secundaria t\u00e9cnica 64, de Los Charcos, dijo valorar mucho el apoyo del Gobernador en las diversas obras educativas y acciones, adem\u00e1s destac\u00f3 que el Mandatario acuda personalmente a conocer las necesidades de los habitantes.<\/p>\n\n\n\n<p>&nbsp;\u201cLe reconozco y le valoro todo su apoyo, lo que hace por este municipio\u201d, afirm\u00f3 el presidente municipal Iv\u00e1n Soto al considerar que las acciones que se han logrado, son un esfuerzo en equipo, como la infraestructura hidr\u00e1ulica, la plaza p\u00fablica, y los programas sociales con techos de l\u00e1minas, cuartos adicionales, dormitorios y las celdas solares, entre otros.<\/p>\n\n\n\n<p>Casi al finalizar la gira, los estudiantes, las familias de la localidad y el gobernador, fueron sorprendidos por la lluvia, por lo que aprovecharon para disfrutar de un momento diferente e inesperado y a su vez estrenaron el domo reci\u00e9n inaugurado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>11 de julio de 2024.- Anunci\u00f3 que las Tarjetas Madre se priorizar\u00e1n en la zona ind\u00edgena y llegar\u00e1n a las mujeres trabajadoras. Para que las familias de las comunidades del Mezquital, cuenten con espacios seguros, puedan convivir sanamente y los estudiantes tengan lugares dignos, el gobernador Esteban Villegas entreg\u00f3 la construcci\u00f3n de la plaza c\u00edvica&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2602"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2602\/revisions"}],"predecessor-version":[{"id":2604,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2602\/revisions\/2604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/2603"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}