{"id":2562,"date":"2024-07-04T02:44:50","date_gmt":"2024-07-04T02:44:50","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2562"},"modified":"2024-07-05T02:46:28","modified_gmt":"2024-07-05T02:46:28","slug":"recibe-ujed-la-mano-de-un-gobernador-amigo-supervisa-esteban-construccion-de-auditorio-y-cafeteria-en-facultad-de-ingenieria","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/recibe-ujed-la-mano-de-un-gobernador-amigo-supervisa-esteban-construccion-de-auditorio-y-cafeteria-en-facultad-de-ingenieria\/","title":{"rendered":"Recibe UJED la mano de un gobernador amigo; supervisa Esteban construcci\u00f3n de auditorio y cafeter\u00eda en Facultad de Ingenier\u00eda"},"content":{"rendered":"\n<p>04 de julio de 2024 <strong>G\u00f3mez Palacio, Dgo.-<\/strong> \u201cLa Universidad Ju\u00e1rez tiene que sentir la mano de un gobernador amigo, un gobernador universitario\u201d, expres\u00f3 el Mandatario Estatal, Esteban Villegas Villarreal al supervisar junto al rector de la M\u00e1xima Casas de Estudios (UJED), Rub\u00e9n Sol\u00eds R\u00edos y la alcaldesa de G\u00f3mez Palacio, Leticia Herrera Ale, la construcci\u00f3n del Gimnasio-Auditorio de la Facultad de Ingenier\u00eda Civil y la cafeter\u00eda del N\u00facleo Universitario del campus en este municipio.<\/p>\n\n\n\n<p>\u201cLe tengo un gran cari\u00f1o a la Universidad, fue la que me dio mi formaci\u00f3n, parte de lo que soy es gracias a la universidad, ah\u00ed empec\u00e9 en la pol\u00edtica y eso me dio la oportunidad para que despu\u00e9s nos invitar\u00e1n a participar en la pol\u00edtica estatal y llegar a gobernador\u201d, dijo Villegas Villarreal al recorrer dichos espacios, donde inicialmente se invertir\u00e1n 7 millones de pesos en el auditorio, con una mezcla de recursos entre la UJED y el Gobierno Estatal;&nbsp; tambi\u00e9n se concluir\u00e1&nbsp; la construcci\u00f3n de una cafeter\u00eda digna para los alumnos laguneros.<\/p>\n\n\n\n<p>\u201cPara m\u00ed siempre son importantes las sociedades de alumnos porque de all\u00ed sal\u00ed\u201d, refrend\u00f3 el Gobernador ante los estudiantes que agradecieron su apoyo para concretar estos dos proyectos importantes para la comunidad universitaria.<\/p>\n\n\n\n<p>El rector de la UJED, Rub\u00e9n Sol\u00eds R\u00edos puntualiz\u00f3 que este auditorio de la Facultad de Ingenier\u00eda Civil&nbsp; beneficiar\u00e1 a m\u00e1s de seis mil estudiantes, incluidos los de la Facultad de Medicina y de Agricultura; su destino ser\u00e1 para la celebraci\u00f3n de eventos con car\u00e1cter oficial, as\u00ed como deportivos que ayudar\u00e1n al desarrollo integral de los j\u00f3venes.<\/p>\n\n\n\n<p>Agreg\u00f3 que la cafeter\u00eda del N\u00facleo Universitario, dar\u00e1 servicio a todas las carreras de la universidad y a la fecha, se le han invertido 4.1 millones de pesos, con lo que se espera estar en posibilidades de ocupar la planta de abajo y brindar servicio. Para concluir la planta alta, har\u00e1n falta 3.4 millones de pesos, mismos que ser\u00e1n aportados por el Gobierno de Esteban, puntualiz\u00f3.<\/p>\n\n\n\n<p>Por su parte, la alcaldesa Leticia Herrera Ale, dio a conocer que en breve se pondr\u00e1 a consideraci\u00f3n del Cabildo su intenci\u00f3n de donar los terrenos que actualmente tiene en comodato la UJED, con el prop\u00f3sito de que crezca esta Casa de Estudios, petici\u00f3n que fue realizada por el Gobernador.<\/p>\n\n\n\n<p>En este recorrido, el Mandatario Estatal estuvo acompa\u00f1ado por la titular de la Secretar\u00eda de Comunicaciones y Obras P\u00fablicas (SECOPE), Ana Rosa Hern\u00e1ndez, del secretario de Educaci\u00f3n, Guillermo Adame Calder\u00f3n y del director del Instituto para la Infraestructura F\u00edsica Educativa del Estado (INIFEED), Emmanuel del Palacio Sicsik.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>04 de julio de 2024 G\u00f3mez Palacio, Dgo.- \u201cLa Universidad Ju\u00e1rez tiene que sentir la mano de un gobernador amigo, un gobernador universitario\u201d, expres\u00f3 el Mandatario Estatal, Esteban Villegas Villarreal al supervisar junto al rector de la M\u00e1xima Casas de Estudios (UJED), Rub\u00e9n Sol\u00eds R\u00edos y la alcaldesa de G\u00f3mez Palacio, Leticia Herrera Ale, la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-2562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango","category-gomez-palacio"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2562"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2562\/revisions"}],"predecessor-version":[{"id":2564,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2562\/revisions\/2564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/2563"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}