{"id":2532,"date":"2024-06-19T21:54:00","date_gmt":"2024-06-19T21:54:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2532"},"modified":"2024-07-02T21:56:00","modified_gmt":"2024-07-02T21:56:00","slug":"juntos-le-cambiamos-el-rostro-a-gomez-palacio-y-sus-calles-esteban-y-lety-re-pavimentan-vialidades-con-apoyo-de-pemex","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/juntos-le-cambiamos-el-rostro-a-gomez-palacio-y-sus-calles-esteban-y-lety-re-pavimentan-vialidades-con-apoyo-de-pemex\/","title":{"rendered":"Juntos le cambiamos el rostro a G\u00f3mez Palacio y sus calles; Esteban y Lety re pavimentan vialidades con apoyo de PEMEX"},"content":{"rendered":"\n<p>19 de junio de 2024.- La meta es llegar al mill\u00f3n de metros cuadrados de pavimentos asf\u00e1lticos.<\/p>\n\n\n\n<p>\u201cEste tipo de obras le van cambiando el rostro a G\u00f3mez Palacio, vamos arrancando la pavimentaci\u00f3n, la idea es llegar a mucho m\u00e1s y poder rehabilitarle a este municipio muchas de sus calles; juntos lo vamos a lograr\u201d, expres\u00f3 el gobernador Esteban Villegas, que junto con la alcaldesa Leticia Herrera, recorrieron y supervisaron la repavimentaci\u00f3n de calles como Den\u00e9vola, 20 de Noviembre y Jes\u00fas Agust\u00edn Castro.<\/p>\n\n\n\n<p>Al recorrer la calle Den\u00e9vola, el Mandatario Estatal mencion\u00f3 que esta avenida, ten\u00eda muchos a\u00f1os que no se le invert\u00eda recurso y ahora,&nbsp; ser\u00e1 diferente, ya que adem\u00e1s de la imagen, cambia la seguridad para la Comarca Lagunera; \u201ciremos cerrando circuitos que nos permitan tener mayor movilidad y los veh\u00edculos ya no van a lastimarse al pasar por calles complejas\u201d, apunt\u00f3.<\/p>\n\n\n\n<p>En esta visita de supervisi\u00f3n, Villegas Villarreal inform\u00f3 que la meta para este a\u00f1o en pavimentaci\u00f3n de calles es de 200 mil metros cuadrados, sin embargo, se buscar\u00e1 gestionar el recurso para llegar al mill\u00f3n de metros cuadrados en arreglos de este tipo.<\/p>\n\n\n\n<p>\u201cGracias Gobernador, estas calles estaban en muy malas condiciones, muy deterioradas y ahora ya quedaron bien, mientras estemos usted y yo, vamos a avanzar mucho m\u00e1s\u201d, asegur\u00f3 la presidenta de G\u00f3mez Palacio, al mencionar que el bulevar Den\u00e9vola es uno de los m\u00e1s transitados, por lo que es de gran beneficio para los gomezpalatinos.<\/p>\n\n\n\n<p>Por su parte, la secretaria de Comunicaciones y Obras P\u00fablicas (SECOPE), Ana Rosa Hern\u00e1ndez, comparti\u00f3 que el recurso de dichas pavimentaciones, se obtuvo gracias a las gestiones del Gobernador con PEMEX, y ahora con estos trabajos, habr\u00e1 m\u00e1s fluidez para quien transita por esta zona, una de las que presenta mayor tr\u00e1fico vehicular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>19 de junio de 2024.- La meta es llegar al mill\u00f3n de metros cuadrados de pavimentos asf\u00e1lticos. \u201cEste tipo de obras le van cambiando el rostro a G\u00f3mez Palacio, vamos arrancando la pavimentaci\u00f3n, la idea es llegar a mucho m\u00e1s y poder rehabilitarle a este municipio muchas de sus calles; juntos lo vamos a lograr\u201d,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2533,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2532"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2532\/revisions"}],"predecessor-version":[{"id":2534,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2532\/revisions\/2534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/2533"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}