{"id":2493,"date":"2024-07-01T09:19:00","date_gmt":"2024-07-01T09:19:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2493"},"modified":"2024-07-02T21:21:03","modified_gmt":"2024-07-02T21:21:03","slug":"inicia-venta-de-boletos-para-toc-toc-la-gira","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/espectaculos\/inicia-venta-de-boletos-para-toc-toc-la-gira\/","title":{"rendered":"Inicia venta de boletos para \u2018Toc Toc\u2019 la gira"},"content":{"rendered":"\n<p>01 de julio de 2024.- Torre\u00f3n, Coahuila.- A partir de este lunes primero de julio, en punto de las 11:11 de la ma\u00f1ana, dar\u00e1 inicio la\u00a0<strong>venta de boletos<\/strong>\u00a0para disfrutar de la\u00a0<strong>obra \u2018Toc Toc\u2019<\/strong>, la gira, la cual se presentar\u00e1 en el<strong>\u00a0Teatro Isauro Mart\u00ednez<\/strong>\u00a0el pr\u00f3ximo 17 de octubre del a\u00f1o en curso, con funciones a las 7:00 pm y 9:00 pm.<\/p>\n\n\n\n<p>TOCTOC es una obra que&nbsp;<strong>trata sobre seis personajes con trastornos obsesivos compulsivos (TOC)<\/strong>, se conocen en la sala de un famoso psiquiatra, con el fin de solucionar sus problemas. Pero el psiquiatra no puede llegar a tiempo, as\u00ed que todos se ven obligados a compartir una espera que parece interminable.<\/p>\n\n\n\n<p>En esta obra se cuenta con la participaci\u00f3n de los actores&nbsp;<strong>Lola Cort\u00e9s, Omar Medina, Raquel Garza, H\u00e9ctor Trejo \u2018Bully\u2019, Armando Hern\u00e1ndez, Dari Romo y Gloria Aura.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>01 de julio de 2024.- Torre\u00f3n, Coahuila.- A partir de este lunes primero de julio, en punto de las 11:11 de la ma\u00f1ana, dar\u00e1 inicio la\u00a0venta de boletos\u00a0para disfrutar de la\u00a0obra \u2018Toc Toc\u2019, la gira, la cual se presentar\u00e1 en el\u00a0Teatro Isauro Mart\u00ednez\u00a0el pr\u00f3ximo 17 de octubre del a\u00f1o en curso, con funciones a las&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2493"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2493\/revisions"}],"predecessor-version":[{"id":2495,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2493\/revisions\/2495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/2494"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}