{"id":2301,"date":"2024-05-05T01:43:25","date_gmt":"2024-05-05T01:43:25","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2301"},"modified":"2024-05-13T01:44:21","modified_gmt":"2024-05-13T01:44:21","slug":"homero-martinez-supervisa-obra-de-catastro-y-area-juridica","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/homero-martinez-supervisa-obra-de-catastro-y-area-juridica\/","title":{"rendered":"Homero Mart\u00ednez supervisa obra de Catastro y \u00e1rea Jur\u00eddica"},"content":{"rendered":"\n<p>05 de mayo de 2024.- Con obras de edificios que sean propiedad del Ayuntamiento de Lerdo representan un ahorro significativo en beneficio de las arcas locales, tal es el caso de la supervisi\u00f3n de la Obra nueva de Castro y Direcci\u00f3n Jur\u00eddica del Municipio la cual registra ya hasta un 75 por ciento de avance en su construcci\u00f3n. <\/p>\n\n\n\n<p>\u201cCuando yo entr\u00e9 en el 2019 se pagaban casi seis millones de pesos al a\u00f1o de puros arrendamientos, el objetivo es quedarse todo ese gasto y que le represente un ahorro a los ciudadanos porque el final ese ahorro representa la oportunidad de que se haga un pavimento, una obra de importancia\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Cit\u00f3 que tambi\u00e9n traen obras donde se hace una supervisi\u00f3n puntual como el Paseo de las Palmas, \u201cya se recarpete\u00f3 todo ese tramo, agradecerle al gobernador Esteban Villegas porque de los compromisos que nos ha ayudado el CREE est\u00e1 avanzando, la Cuauht\u00e9moc pr\u00e1cticamente ya se est\u00e1 terminando la pavimentaci\u00f3n, Secope tambi\u00e9n nos est\u00e1 ayudando con la Prolongaci\u00f3n Agust\u00edn Castro tambi\u00e9n se est\u00e1 recarpeteando\u201d, a\u00f1adi\u00f3.Homero Mart\u00ednez Cabrera, alcalde de Lerdo, destac\u00f3 que como cada s\u00e1bado a trav\u00e9s de la Direcci\u00f3n de Obras P\u00fablicas realiza un recorrido donde personalmente supervisa las obras y acciones a cargo del Ayuntamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>05 de mayo de 2024.- Con obras de edificios que sean propiedad del Ayuntamiento de Lerdo representan un ahorro significativo en beneficio de las arcas locales, tal es el caso de la supervisi\u00f3n de la Obra nueva de Castro y Direcci\u00f3n Jur\u00eddica del Municipio la cual registra ya hasta un 75 por ciento de avance&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2301","post","type-post","status-publish","format-standard","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2301"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2301\/revisions"}],"predecessor-version":[{"id":2302,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2301\/revisions\/2302"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}