{"id":2245,"date":"2024-04-12T05:21:46","date_gmt":"2024-04-12T05:21:46","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2245"},"modified":"2024-04-12T05:21:46","modified_gmt":"2024-04-12T05:21:46","slug":"alcaldesa-leticia-herrera-ale-supervisa-trabajos-de-instalacion-de-colector-en-la-colonia-fovissste","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/gomez-palacio\/alcaldesa-leticia-herrera-ale-supervisa-trabajos-de-instalacion-de-colector-en-la-colonia-fovissste\/","title":{"rendered":"Alcaldesa Leticia Herrera Ale supervisa trabajos de instalaci\u00f3n de colector en la colonia Fovissste"},"content":{"rendered":"\n<p>12 de abril de 2024.- La\u00a0<strong>presidenta municipal, Leticia Herrera Ale<\/strong>, acudi\u00f3 a la\u00a0<strong>colonia Fovissste\u00a0<\/strong>para supervisar los trabajos de instalaci\u00f3n del nuevo colector que actualmente se est\u00e1 instalando sobre la calle Gustavo Baz, de esta colonia. Durante la visita, el titular del organismo operador de agua de G\u00f3mez Palacio, indic\u00f3 que en este lugar se reponen 432 metros de\u00a0<strong>tuber\u00eda de drenaje de polietileno de alta densidad de 12\u201d de di\u00e1metro.<\/strong> <\/p>\n\n\n\n<p>Adem\u00e1s, dijo que a esta nueva tuber\u00eda&nbsp;<strong>se conectar\u00e1n 80 descargas sanitarias de 6\u201d de di\u00e1metro.<\/strong><\/p>\n\n\n\n<p>Estos trabajos se llevan a cabo con recursos del Ramo 33 y son una respuesta a los compromisos asumidos por la presidenta municipal, en una reciente&nbsp;<strong>Audiencia P\u00fablica celebrada con vecinos de las colonias Fovissste y Bellavista.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>12 de abril de 2024.- La\u00a0presidenta municipal, Leticia Herrera Ale, acudi\u00f3 a la\u00a0colonia Fovissste\u00a0para supervisar los trabajos de instalaci\u00f3n del nuevo colector que actualmente se est\u00e1 instalando sobre la calle Gustavo Baz, de esta colonia. Durante la visita, el titular del organismo operador de agua de G\u00f3mez Palacio, indic\u00f3 que en este lugar se reponen&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gomez-palacio"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2245"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2245\/revisions"}],"predecessor-version":[{"id":2247,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2245\/revisions\/2247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/2246"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}