{"id":2107,"date":"2024-02-27T19:20:11","date_gmt":"2024-02-27T19:20:11","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=2107"},"modified":"2024-02-29T19:21:33","modified_gmt":"2024-02-29T19:21:33","slug":"anuncia-esteban-ampliacion-de-empresa-coreana-yura-en-lerdo-generara-800-empleos-directos","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/anuncia-esteban-ampliacion-de-empresa-coreana-yura-en-lerdo-generara-800-empleos-directos\/","title":{"rendered":"Anuncia Esteban ampliaci\u00f3n de empresa coreana Yura en Lerdo; generar\u00e1 800 empleos directos"},"content":{"rendered":"\n<p>27 de febrero de 2024.-Se trata de un consorcio de autopartes, arneses, conectores de alto voltaje y componentes el\u00e9ctricos, que proyecta una inversi\u00f3n inicial de 80 mdp.<\/p>\n\n\n\n<p>En Durango ponemos la muestra de que se pueden hacer las cosas bien y que se cumple la palabra, se\u00f1al\u00f3 el gobernador Esteban Villegas Villarreal al anunciar la ampliaci\u00f3n de Yura, una empresa de fabricaci\u00f3n de autopartes, arneses, conectores de alto voltaje y componentes el\u00e9ctricos en Lerdo.<\/p>\n\n\n\n<p>Se trata de una inversi\u00f3n aproximada de 80 millones de pesos y la generaci\u00f3n de 800 nuevos empleos directos tan solo con esta nueva planta, que arranca de forma inmediata con 200 espacios este mismo lunes 26 de febrero para realizar los primeros trabajos de construcci\u00f3n y acondicionamiento de la nave.&nbsp;<\/p>\n\n\n\n<p>El Mandatario Estatal, agreg\u00f3 que, adicionalmente se activar\u00e1n todos los sectores comerciales, con los empleos que se generar\u00e1n de manera indirecta y a favor de la inyecci\u00f3n del flujo econ\u00f3mico de la regi\u00f3n lagunera con esta compa\u00f1\u00eda que se ubicar\u00e1 por el Perif\u00e9rico, frente a Siete Leguas y que favorece a la gente de ciudad Jard\u00edn.<\/p>\n\n\n\n<p>Esta nueva empresa coreana es Yura Corporation, se especializa en el dise\u00f1o, desarrollo y fabricaci\u00f3n de productos electr\u00f3nicos para autom\u00f3viles, incluidos mazos de cables y otros implementos; la empresa se fund\u00f3 en 1993, posteriormente, su Instituto de Investigaci\u00f3n se combin\u00f3 con el de Hanil Tech, y con las habilidades t\u00e9cnicas y el conocimiento acumulado por Hanil Tech desde su creaci\u00f3n en 1970, Yura Corporation ha continuado el desarrollo de sus tecnolog\u00edas.<\/p>\n\n\n\n<p>Con este convenio, que se suma a las otras tres nuevas inversiones del 2024 anunciadas por Esteban, que consiste la ampliaci\u00f3n de esta empresa, es una muestra m\u00e1s de que el estado se posiciona en el centro del mundo, en la industria y la mano de obra calificada de su gente con gran valor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>27 de febrero de 2024.-Se trata de un consorcio de autopartes, arneses, conectores de alto voltaje y componentes el\u00e9ctricos, que proyecta una inversi\u00f3n inicial de 80 mdp. En Durango ponemos la muestra de que se pueden hacer las cosas bien y que se cumple la palabra, se\u00f1al\u00f3 el gobernador Esteban Villegas Villarreal al anunciar la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=2107"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2107\/revisions"}],"predecessor-version":[{"id":2109,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/2107\/revisions\/2109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/2108"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=2107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=2107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=2107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}