{"id":1840,"date":"2024-01-08T17:28:15","date_gmt":"2024-01-08T17:28:15","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=1840"},"modified":"2024-01-16T17:36:56","modified_gmt":"2024-01-16T17:36:56","slug":"regresan-450-mil-alumnos-a-clases-este-2024-el-ano-de-durango-gobierno-de-esteban-va-por-primeros-lugares-en-educacion-en-el-pais","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/regresan-450-mil-alumnos-a-clases-este-2024-el-ano-de-durango-gobierno-de-esteban-va-por-primeros-lugares-en-educacion-en-el-pais\/","title":{"rendered":"Regresan 450 mil alumnos a clases este 2024, el a\u00f1o de Durango; Gobierno de Esteban va por primeros lugares en educaci\u00f3n en el pa\u00eds"},"content":{"rendered":"\n<p>Se mejorar\u00e1 la ense\u00f1anza con las Aulas Virtuales, el ingl\u00e9s sabatino y se incentivar\u00e1 a alumnos a descubrir su potencial al fortalecer la lectura, escritura y las matem\u00e1ticas.<\/p>\n\n\n\n<p>08 de enero de 2024.-M\u00e1s de 450 mil alumnos de educaci\u00f3n b\u00e1sica, hoy reanudaron clases en este 2024, el a\u00f1o de Durango, y aunque con un ambiente fr\u00edo, muy contentos por su regreso a las aulas, inform\u00f3 el secretario de Educaci\u00f3n, Guillermo Adame Calder\u00f3n, tras se\u00f1alar que como lo instruy\u00f3 el gobernador Esteban Villegas, se contin\u00faa con un ritmo de mejora en la ense\u00f1anza para posicionar al Sistema Educativo de Durango como uno de los primeros en el \u00e1mbito nacional, y lo m\u00e1s importante, reflejado en los estudiantes.<\/p>\n\n\n\n<p>El titular de la SEED, apunt\u00f3 que en este 2024, se busca avanzar en dicho objetivo de posicionar a la entidad y sobre todo, incentivar a los alumnos a que descubran su potencial, con la implementaci\u00f3n de programas que desarrollen sus conocimientos y habilidades, como el ingl\u00e9s sabatino, las Aulas Interactivas Digitales y el fortalecimiento a la lectura, escritura y las matem\u00e1ticas.<\/p>\n\n\n\n<p>La Administraci\u00f3n Estatal ha implementado estrategias para fomentar la actividad f\u00edsica en las escuelas, con \u201cAct\u00edvate Durango\u201d, combinado con las estrategias impulsadas en coordinaci\u00f3n con el Gobierno Federal, a trav\u00e9s del programa \u201cSi te drogas, te da\u00f1as\u201d, todo incluido en el Programa Educativo 2023 &#8211; 2028.<\/p>\n\n\n\n<p>Cabe destacar que, alrededor de 450 mil estudiantes de los cinco mil planteles de preescolar, primaria y secundaria de todo el estado, reiniciaron clases luego del periodo vacacional correspondiente al mes de diciembre.<\/p>\n\n\n\n<p>De la misma manera, m\u00e1s de 20 mil docentes recibieron a los alumnos en las aulas, luego del taller intensivo de formaci\u00f3n que se llev\u00f3 a cabo la semana anterior.<\/p>\n\n\n\n<p>Por otro lado, los trabajadores de la educaci\u00f3n han contado con el pleno respeto a sus prestaciones laborales, as\u00ed como capacitaciones de talla internacional, lo que se traduce en mejores oportunidades para los maestros, la dignificaci\u00f3n de su labor que favorece a la preparaci\u00f3n de los estudiantes para un mejor futuro, en especial en este 2024, el a\u00f1o de Durango, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se mejorar\u00e1 la ense\u00f1anza con las Aulas Virtuales, el ingl\u00e9s sabatino y se incentivar\u00e1 a alumnos a descubrir su potencial al fortalecer la lectura, escritura y las matem\u00e1ticas. 08 de enero de 2024.-M\u00e1s de 450 mil alumnos de educaci\u00f3n b\u00e1sica, hoy reanudaron clases en este 2024, el a\u00f1o de Durango, y aunque con un ambiente&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1840","post","type-post","status-publish","format-standard","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=1840"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1840\/revisions"}],"predecessor-version":[{"id":1842,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1840\/revisions\/1842"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=1840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=1840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=1840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}