{"id":1831,"date":"2024-01-05T17:20:02","date_gmt":"2024-01-05T17:20:02","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=1831"},"modified":"2024-01-16T17:22:16","modified_gmt":"2024-01-16T17:22:16","slug":"con-la-disciplina-financiera-del-gobierno-de-esteban-33-mil-trabajadores-recibiran-la-segunda-parte-de-su-aguinaldo","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/con-la-disciplina-financiera-del-gobierno-de-esteban-33-mil-trabajadores-recibiran-la-segunda-parte-de-su-aguinaldo\/","title":{"rendered":"Con la disciplina financiera del Gobierno de Esteban, 33 mil trabajadores recibir\u00e1n la segunda parte de su aguinaldo"},"content":{"rendered":"\n<p>Con esto se refrenda el compromiso del Gobierno Estatal con la base trabajadora: Bertha Cristina Orrante Rojas, secretaria de Finanzas.<\/p>\n\n\n\n<p>05 de enero de 2024.-El Gobierno de Estado cumplir\u00e1 en tiempo y forma con el pago de la segunda parte del aguinaldo para este 8 de enero del 2024, a poco m\u00e1s de 33 mil trabajadores estatales, gracias a la disciplina financiera implementada por el mandatario estatal, Esteban Villegas Villarreal, anunci\u00f3 la titular de la Secretar\u00eda de Finanzas y de Administraci\u00f3n del Estado, Bertha Cristina Orrante Rojas.<\/p>\n\n\n\n<p>Detall\u00f3 que los trabajadores sindicalizados, de confianza y el de la educaci\u00f3n pertenecientes a la secci\u00f3n 44, del SNTE, ser\u00e1n favorecidos con esta prestaci\u00f3n, con lo que se refrenda el cumplimiento&nbsp; que tiene el&nbsp; Gobierno del Estado con sus trabajadores.&nbsp;<\/p>\n\n\n\n<p>Lo anterior se logr\u00f3 gracias a la pol\u00edtica financiera con la que se ha conducido este Gobierno, plasmada en disciplina, responsabilidad y orden y que se ha venido implementando desde el inicio del primer d\u00eda del sexenio.&nbsp;<\/p>\n\n\n\n<p>Cabe destacar que en diciembre, se realiz\u00f3 de manera puntual la dispersi\u00f3n de la primera parte del recurso para cumplir con la primera parte del aguinaldo a todos los trabajadores del Estado, y el lunes de la pr\u00f3xima semana, se contar\u00e1 con la segunda parte de manera puntual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con esto se refrenda el compromiso del Gobierno Estatal con la base trabajadora: Bertha Cristina Orrante Rojas, secretaria de Finanzas. 05 de enero de 2024.-El Gobierno de Estado cumplir\u00e1 en tiempo y forma con el pago de la segunda parte del aguinaldo para este 8 de enero del 2024, a poco m\u00e1s de 33 mil&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=1831"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1831\/revisions"}],"predecessor-version":[{"id":1833,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1831\/revisions\/1833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/1832"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=1831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=1831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=1831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}