{"id":1582,"date":"2023-12-05T00:50:41","date_gmt":"2023-12-05T00:50:41","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=1582"},"modified":"2023-12-05T00:50:41","modified_gmt":"2023-12-05T00:50:41","slug":"no-prescribiran-delitos-contra-menores-congreso","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/uncategorized\/congreso-de-durango\/no-prescribiran-delitos-contra-menores-congreso\/","title":{"rendered":"No prescribir\u00e1n delitos contra menores: Congreso"},"content":{"rendered":"\n<p>Establecen derecho a la pensi\u00f3n compensatoria<\/p>\n\n\n\n<p>04 de diciembre de 2023. Dentro de las reformas se incluye como conducta delictiva la entrega de apoyos il\u00edcita a familiares: Paty Jim\u00e9nez<\/p>\n\n\n\n<p>El Congreso de Estado aprob\u00f3 las reformas al C\u00f3digo Civil y Penal con la finalidad que no prescriban los delitos contra menores de edad v\u00edctimas de abuso sexual, establecer la pensi\u00f3n compensatoria, castigar el abuso de poder en la entrega de apoyos sociales a familiares y en materia de comprobaci\u00f3n de delitos.<\/p>\n\n\n\n<p>Al hacer uso de la tribuna, la presidenta de la Comisi\u00f3n de Justicia, Paty Jim\u00e9nez Delgado, explic\u00f3 que la primera reforma al C\u00f3digo Penal tiene el prop\u00f3sito de eliminar el concepto \u201creiteradamente\u201d del tipo delictivo de acoso sexual, con la finalidad de que se deje la carga excesiva de requisitos que se tienen que comprobar para la configuraci\u00f3n de este il\u00edcito.<\/p>\n\n\n\n<p>En relaci\u00f3n a las modificaciones al C\u00f3digo Civil, se\u00f1al\u00f3 que establece que en los casos en que el da\u00f1o moral se ocasione a menores de 12 a\u00f1os v\u00edctimas de violaci\u00f3n, abuso sexual o pederastia, la acci\u00f3n para exigir la reparaci\u00f3n no prescribir\u00e1.<\/p>\n\n\n\n<p>La segunda reforma a este mismo ordenamiento describir la pensi\u00f3n compensatoria que precisa que el c\u00f3nyuge que durante el matrimonio se haya dedicado a las labores del hogar y\/o al cuidado de los hijos y que no hubiere generado los medios para tener independencia econ\u00f3mica durante el matrimonio, tendr\u00e1 derecho a una pensi\u00f3n compensatoria al momento del divorcio.<\/p>\n\n\n\n<p>De esta manera, en la resoluci\u00f3n se fijar\u00e1n las bases para actualizar la pensi\u00f3n y las garant\u00edas para su efectividad, donde el derecho a la pensi\u00f3n alimenticia compensatoria se extingue cuando el acreedor contraiga nuevas nupcias o se una en concubinato o haya transcurrido un t\u00e9rmino igual a la duraci\u00f3n del matrimonio.<\/p>\n\n\n\n<p>Finalmente, explic\u00f3 que en el C\u00f3digo Penal Federal, en materia del delito de ejercicio abusivo de funciones, incluye como conducta delictiva el que los apoyos provenientes de programas sociales sean entregados il\u00edcitamente por alg\u00fan servidor p\u00fablico en favor de este \u00faltimo o de su c\u00f3nyuge, descendiente o ascendiente, parientes por consanguinidad o afinidad hasta el cuarto grado, a cualquier tercero con el que tenga v\u00ednculos afectivos, econ\u00f3micos o de dependencia administrativa directa, socios o sociedades de las que el servidor p\u00fablico o las personas antes referidas formen parte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Establecen derecho a la pensi\u00f3n compensatoria 04 de diciembre de 2023. Dentro de las reformas se incluye como conducta delictiva la entrega de apoyos il\u00edcita a familiares: Paty Jim\u00e9nez El Congreso de Estado aprob\u00f3 las reformas al C\u00f3digo Civil y Penal con la finalidad que no prescriban los delitos contra menores de edad v\u00edctimas de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-congreso-de-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=1582"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1582\/revisions"}],"predecessor-version":[{"id":1584,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1582\/revisions\/1584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/1583"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=1582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=1582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=1582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}