{"id":1535,"date":"2023-11-29T15:16:09","date_gmt":"2023-11-29T15:16:09","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=1535"},"modified":"2023-11-30T15:17:19","modified_gmt":"2023-11-30T15:17:19","slug":"lerdo-es-sede-de-la-reinstalacion-del-sipinna-para-la-proteccion-de-infantes","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/lerdo-es-sede-de-la-reinstalacion-del-sipinna-para-la-proteccion-de-infantes\/","title":{"rendered":"Lerdo es sede de la reinstalaci\u00f3n del SIPINNA para la protecci\u00f3n de infantes"},"content":{"rendered":"\n<p>29 de noviembre de 2023.Fue en el Sal\u00f3n Azul de la Presidencia Municipal de Lerdo donde se llev\u00f3 a cabo la reinstalaci\u00f3n del Sistema Nacional de Protecci\u00f3n de Ni\u00f1as, Ni\u00f1os y Adolescentes. Ah\u00ed el alcalde Homero Mart\u00ednez Cabrera celebr\u00f3 el trabajo coordinado que existe entre las instancias presentes.<\/p>\n\n\n\n<p>Adem\u00e1s de la Procuradora para la Defensa de Ni\u00f1as, Ni\u00f1os y Adolescentes, Laura Cristina Meraz, en este encuentro participaron los directivos y representantes de la Segunda Visitadur\u00eda de la Comisi\u00f3n Estatal de los Derechos Humanos, Vicefiscal\u00eda, Centro de Integraci\u00f3n Juvenil, DIF Lerdo, Secretar\u00eda del Ayuntamiento, Secretar\u00eda T\u00e9cnica, Protecci\u00f3n Civil, Seguridad P\u00fablica, Juzgado Municipal, Instituto de la Mujer, Instituto de la Juventud, Educaci\u00f3n, Salud Municipal, Desarrollo Social, Tesorer\u00eda, y la S\u00edndico Municipal Alina Rivera, quienes, adem\u00e1s, tomaron protesta. Teniendo como objetivo en com\u00fan, el salvaguardar la integridad de los menores de edad, garantizar su bienestar, y que ning\u00fan ni\u00f1o viva en situaci\u00f3n calle ni se enfrente a los peligros que eso conlleva, como el abuso y consumo de sustancias nocivas para la salud<\/p>\n","protected":false},"excerpt":{"rendered":"<p>29 de noviembre de 2023.Fue en el Sal\u00f3n Azul de la Presidencia Municipal de Lerdo donde se llev\u00f3 a cabo la reinstalaci\u00f3n del Sistema Nacional de Protecci\u00f3n de Ni\u00f1as, Ni\u00f1os y Adolescentes. Ah\u00ed el alcalde Homero Mart\u00ednez Cabrera celebr\u00f3 el trabajo coordinado que existe entre las instancias presentes. Adem\u00e1s de la Procuradora para la Defensa&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=1535"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1535\/revisions"}],"predecessor-version":[{"id":1537,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1535\/revisions\/1537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/1536"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=1535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=1535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=1535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}