{"id":1300,"date":"2023-10-16T05:25:00","date_gmt":"2023-10-16T05:25:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=1300"},"modified":"2023-10-30T17:25:58","modified_gmt":"2023-10-30T17:25:58","slug":"en-durango-los-jovenes-suenan-en-grande-inaugura-esteban-nacional-deportivo-del-tecnm","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/durango\/en-durango-los-jovenes-suenan-en-grande-inaugura-esteban-nacional-deportivo-del-tecnm\/","title":{"rendered":"En Durango los j\u00f3venes sue\u00f1an en grande; inaugura Esteban, Nacional Deportivo del TecNM"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">&nbsp;Esteban es amigo del Tecnol\u00f3gico y sin su apoyo, este a\u00f1o no hubiera sido posible la inauguraci\u00f3n de los juegos deportivos: Director del ITD.<\/h2>\n\n\n\n<p>16 de octubre de 2023. \u201cBienvenidos a esta tierra, Durango es su casa y as\u00ed se van a sentir\u201d, les expres\u00f3 el gobernador Esteban Villegas Villarreal a m\u00e1s de dos mil 600 alumnos deportistas de todo el pa\u00eds, que participar\u00e1n en el LXV Evento Nacional Deportivo del Tecnol\u00f3gico Nacional de M\u00e9xico, el cual, por sexta ocasi\u00f3n se realiza en la entidad duranguense.<\/p>\n\n\n\n<p>Con gran algarab\u00eda estudiantil, el \u201cHu\u00e9lum, Hu\u00e9lum \u00a1Gloria!\u201d reson\u00f3 a una sola voz en el estadio&nbsp; de b\u00e9isbol Francisco Villa, donde el Gobernador junto al \u00e1rbitro profesional Marco Antonio \u201cel Gato\u201d Ortiz, dieron por inaugurados los juegos deportivos donde atletas y entrenadores demostrar\u00e1n su talento en las diversas disciplinas que se llevar\u00e1n a cabo del 14 al 19 de octubre.<\/p>\n\n\n\n<p>\u201cEsteban es un referente amigo del Tecnol\u00f3gico, sin \u00e9l, este a\u00f1o no hubiera sido posible la inauguraci\u00f3n de estos juegos deportivos\u201d, manifest\u00f3 el director del Tecnol\u00f3gico de Durango, Guillermo de Anda Rodr\u00edguez, al reconocer el apoyo y respaldo del Gobernador en la educaci\u00f3n.<\/p>\n\n\n\n<p>Tambi\u00e9n, destac\u00f3 que desde que los deportistas visitantes pisaron esta tierra, sintieron la calidez \u201cdesde el hotel, restaurantes y la gente con quienes conviven, los tratar\u00e1n como si fuera su propia familia\u201d, les dijo al asegurar que eso s\u00f3lo es posible en un lugar donde se vive en paz y armon\u00eda, lo cual es un gran reflejo del excelente trabajo del gobierno de Esteban Villegas.<\/p>\n\n\n\n<p>En el marco de la gran inauguraci\u00f3n, llena de color y emoci\u00f3n, el Mandatario Estatal junto a la secretaria de Extensi\u00f3n y Vinculaci\u00f3n del TecNM, Andrea Z\u00e1rate Fuentes, entreg\u00f3 reconocimientos a entrenadores de diferentes disciplinas deportivas por su trabajo y trayectoria.<\/p>\n\n\n\n<p>Al otorgar las facilidades para la realizaci\u00f3n de este evento nacional, una vez m\u00e1s, el Gobierno de Esteban, refrend\u00f3 su compromiso para apoyar y fomentar el deporte en la entidad, motivando a los j\u00f3venes a so\u00f1ar en grande.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Esteban es amigo del Tecnol\u00f3gico y sin su apoyo, este a\u00f1o no hubiera sido posible la inauguraci\u00f3n de los juegos deportivos: Director del ITD. 16 de octubre de 2023. \u201cBienvenidos a esta tierra, Durango es su casa y as\u00ed se van a sentir\u201d, les expres\u00f3 el gobernador Esteban Villegas Villarreal a m\u00e1s de dos mil&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1300","post","type-post","status-publish","format-standard","hentry","category-durango"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=1300"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1300\/revisions"}],"predecessor-version":[{"id":1301,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1300\/revisions\/1301"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=1300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=1300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=1300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}