{"id":1198,"date":"2023-10-01T05:16:00","date_gmt":"2023-10-01T05:16:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=1198"},"modified":"2023-10-03T17:17:25","modified_gmt":"2023-10-03T17:17:25","slug":"celebran-110-aniversario-de-la-conformacion-de-la-division-del-norte","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/lerdo\/celebran-110-aniversario-de-la-conformacion-de-la-division-del-norte\/","title":{"rendered":"Celebran 110 aniversario de la Conformaci\u00f3n de la Divisi\u00f3n del Norte"},"content":{"rendered":"\n<p>01 de octubre de 2023.En Villa La Loma, el Presidente Municipal Homero Mart\u00ednez Cabrera recibi\u00f3 de manos del personaje del General Francisco Villa el l\u00e1baro patrio, y a su vez lo entreg\u00f3 a la escolta para hacer los respectivos honores a la bandera.<\/p>\n\n\n\n<p>El alcalde de Lerdo Homero Mart\u00ednez, dijo sentirse orgulloso del municipio de Lerdo, que sea reconocido como La Cuna de la Divisi\u00f3n del Norte y que se cuente con un recinto hist\u00f3rico, como lo es La Ex Hacienda La Loma, Durango, pues ah\u00ed naci\u00f3 la unificaci\u00f3n de las fuerzas armadas de Chihuahua y Durango.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>01 de octubre de 2023.En Villa La Loma, el Presidente Municipal Homero Mart\u00ednez Cabrera recibi\u00f3 de manos del personaje del General Francisco Villa el l\u00e1baro patrio, y a su vez lo entreg\u00f3 a la escolta para hacer los respectivos honores a la bandera. El alcalde de Lerdo Homero Mart\u00ednez, dijo sentirse orgulloso del municipio de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lerdo"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=1198"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1198\/revisions"}],"predecessor-version":[{"id":1200,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1198\/revisions\/1200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/1199"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=1198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=1198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=1198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}