{"id":1161,"date":"2023-10-02T04:53:00","date_gmt":"2023-10-02T04:53:00","guid":{"rendered":"http:\/\/lagumex.mx\/index\/?p=1161"},"modified":"2023-10-03T16:54:17","modified_gmt":"2023-10-03T16:54:17","slug":"inauguran-congreso-estatal-de-cultura-fisica-y-deporte-coahuila-2023","status":"publish","type":"post","link":"https:\/\/lagumex.mx\/index\/uncategorized\/uac\/uac-uac\/coahuila-coahuila\/inauguran-congreso-estatal-de-cultura-fisica-y-deporte-coahuila-2023\/","title":{"rendered":"INAUGURAN \u2018CONGRESO ESTATAL DE CULTURA F\u00cdSICA Y DEPORTE COAHUILA 2023\u2019"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 2 de Octubre de 2023.- Con la presencia de Alina Garza Herrera, Directora General del INEDEC, arranc\u00f3 el Congreso Estatal de Cultura F\u00edsica y Deporte de Coahuila 2023, que tuvo como sede a Torre\u00f3n.<\/p>\n\n\n\n<p>Las instalaciones del Auditorio \u201cJuan Ignacio de Noyola\u201d, ubicado al interior de la Universidad Iberoamericana, fueron la sede del evento.<\/p>\n\n\n\n<p>En este evento estuvieron presentes, adem\u00e1s, David Flores Lavenant, diputado local, y Flor Renter\u00eda, Coordinadora de Servicios Educativos en la Regi\u00f3n Laguna.<\/p>\n\n\n\n<p>Este s\u00e1bado y domingo continuar\u00e1 la actividad con diferentes ponencias y expositores con la intenci\u00f3n de nutrir a\u00fan m\u00e1s el tema deportivo para todos los representantes de los municipios del Estado de Coahuila.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila de Zaragoza; a 2 de Octubre de 2023.- Con la presencia de Alina Garza Herrera, Directora General del INEDEC, arranc\u00f3 el Congreso Estatal de Cultura F\u00edsica y Deporte de Coahuila 2023, que tuvo como sede a Torre\u00f3n. Las instalaciones del Auditorio \u201cJuan Ignacio de Noyola\u201d, ubicado al interior de la Universidad Iberoamericana, fueron&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila-coahuila"],"_links":{"self":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/comments?post=1161"}],"version-history":[{"count":1,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1161\/revisions"}],"predecessor-version":[{"id":1163,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/posts\/1161\/revisions\/1163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media\/1162"}],"wp:attachment":[{"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/media?parent=1161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/categories?post=1161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lagumex.mx\/index\/wp-json\/wp\/v2\/tags?post=1161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}